{"id":49279,"date":"2022-09-19T14:45:23","date_gmt":"2022-09-19T12:45:23","guid":{"rendered":"https:\/\/help.heredis.com\/delete-a-person-on-heredis-android\/"},"modified":"2022-09-19T14:49:13","modified_gmt":"2022-09-19T12:49:13","slug":"delete-a-person-on-heredis-android","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/","title":{"rendered":"Delete a person on Heredis Android"},"content":{"rendered":"<p>You have made a mistake and want to remove a person from your genealogy on Heredis Android?<\/p>\n<p>Navigate to the person you want to edit.<br \/>\nTap the person&#8217;s box in the <strong>Immediate Family<\/strong>&amp;nbsp; or the <strong>Person Details<\/strong> tab.<br \/>\nPress the <strong>pencil<\/strong> to enter edit mode.<\/p>\n<p>Swipe down and down to see what additional topics are available.<\/p>\n<p>Press the <strong>Delete Person <\/strong>button.<\/p>\n<p><strong>Note<\/strong>: The root person, at the base of the tree, cannot be deleted. To be able to delete it, you must first change the root person. See also <a href=\"https:\/\/help.heredis.com\/en\/change-root-person-on-heredis-android\/\" target=\"_blank\" rel=\"noopener noreferrer\">Change root person on Heredis Android<\/a>.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-49272\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg\" alt=\"\" width=\"225\" height=\"500\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg 225w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en-135x300.jpg 135w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>You have made a mistake and want to remove a person from your genealogy on Heredis Android?<\/p>\n<p>Navigate to the [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[146],"tags":[],"class_list":["post-49279","post","type-post","status-publish","format-standard","hentry","category-ios-android"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delete a person on Heredis Android - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delete a person on Heredis Android - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"You have made a mistake and want to remove a person from your genealogy on Heredis Android?  Navigate to the [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-19T12:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-19T12:49:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg\" \/>\n<meta name=\"author\" content=\"Helene Debacq\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene Debacq\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/\"},\"author\":{\"name\":\"Helene Debacq\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\"},\"headline\":\"Delete a person on Heredis Android\",\"datePublished\":\"2022-09-19T12:45:23+00:00\",\"dateModified\":\"2022-09-19T12:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/\"},\"wordCount\":104,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiche_indi2_android_en.jpg\",\"articleSection\":[\"iOS and Android mobile versions\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/\",\"name\":\"Delete a person on Heredis Android - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiche_indi2_android_en.jpg\",\"datePublished\":\"2022-09-19T12:45:23+00:00\",\"dateModified\":\"2022-09-19T12:49:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiche_indi2_android_en.jpg\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/fiche_indi2_android_en.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/delete-a-person-on-heredis-android\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delete a person on Heredis Android\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\",\"name\":\"Helene Debacq\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/en\\\/author\\\/helene-debacqheredis-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delete a person on Heredis Android - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/","og_locale":"en_US","og_type":"article","og_title":"Delete a person on Heredis Android - Heredis Help Knowledgebase","og_description":"You have made a mistake and want to remove a person from your genealogy on Heredis Android?  Navigate to the [...]","og_url":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2022-09-19T12:45:23+00:00","article_modified_time":"2022-09-19T12:49:13+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg","type":"","width":"","height":""}],"author":"Helene Debacq","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Helene Debacq"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/"},"author":{"name":"Helene Debacq","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0"},"headline":"Delete a person on Heredis Android","datePublished":"2022-09-19T12:45:23+00:00","dateModified":"2022-09-19T12:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/"},"wordCount":104,"image":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg","articleSection":["iOS and Android mobile versions"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/","url":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/","name":"Delete a person on Heredis Android - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg","datePublished":"2022-09-19T12:45:23+00:00","dateModified":"2022-09-19T12:49:13+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/fiche_indi2_android_en.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/en\/delete-a-person-on-heredis-android\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/en\/"},{"@type":"ListItem","position":2,"name":"Delete a person on Heredis Android"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0","name":"Helene Debacq","url":"https:\/\/help.heredis.com\/en\/author\/helene-debacqheredis-com\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/posts\/49279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/comments?post=49279"}],"version-history":[{"count":2,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/posts\/49279\/revisions"}],"predecessor-version":[{"id":49285,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/posts\/49279\/revisions\/49285"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/media?parent=49279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/categories?post=49279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/en\/wp-json\/wp\/v2\/tags?post=49279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}