{"id":54944,"date":"2025-09-02T14:00:51","date_gmt":"2025-09-02T12:00:51","guid":{"rendered":"https:\/\/help.heredis.com\/?p=54944"},"modified":"2025-11-13T16:04:12","modified_gmt":"2025-11-13T15:04:12","slug":"einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/","title":{"rendered":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8220;&#8220;]Heredis erm\u00f6glicht die Eingabe einer Vielzahl von Daten. Dazu geh\u00f6ren auch Nach- oder Familiennamen.<\/p>\n<p>Heredis verf\u00fcgt daher \u00fcber ein Feld <strong>Nachname<\/strong> in der Eingabebereichen einer Person.<\/p>\n<p>Lesen Sie die folgenden Artikel zu den verschiedenen M\u00f6glichkeiten:<br \/>\n<a href=\"https:\/\/help.heredis.com\/de\/49764\/\">Eine Persone ohne Verbindungen\u00a0erstellen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/partner-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">Partner hinzuf\u00fcgen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/personen-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">Personen hinzuf\u00fcgen<\/a><a href=\"https:\/\/help.heredis.com\/de\/andere-verbundene-personen-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">, Andere verbundene Personen hinzuf\u00fcgen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">Zeugen und Teilnehmer hinzuf\u00fcgen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/kinder-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">Kinder hinzuf\u00fcgen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/eltern-hinzufuegen\/\" target=\"_blank\" rel=\"noopener\">Eltern hinzuf\u00fcgen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/familiengruppendaten-eingeben\/\" target=\"_blank\" rel=\"noopener\">Familiengruppendaten eingeben<\/a>.<\/p>\n<h3>Einen einfachen Nachnamen eingeben<\/h3>\n<p>In der Ahnenforschung kann es vorkommen, dass f\u00fcr den Nachnamen einer Person mehrere Schreibweisen existieren.<br \/>\nW\u00e4hlen Sie die Schreibweise aus, die Sie m\u00f6chten. Sie k\u00f6nnen diese bei Bedarf \u00e4ndern.<\/p>\n<p>Wir empfehlen Ihnen, den Geburtsnamen oder den Nachnamen, der am h\u00e4ufigsten verwendet wird, anzugeben.<br \/>\nGeben Sie alle anderen Schreibweisen im Reiter <strong>Weitere Namen<\/strong> f\u00fcr diese Person ein. Siehe auch den Artikel <a href=\"https:\/\/help.heredis.com\/de\/weitere-namen\/\" target=\"_blank\" rel=\"noopener\">Weitere Namen<\/a>.<\/p>\n<p>Zum Beispiel findet sich die Schreibweise Schmidt auf der Geburtsurkunde und Schmid auf der Heiratsurkunde.<\/p>\n<p>Heredis geht davon aus, dass es einen Eintrag pro eingegebenen Nachnamen gibt. Wenn Sie zus\u00e4tzliche Nachnamen dem Reiter <strong>Weitere Namen<\/strong> hinzugef\u00fcgt haben, wird Heredis diese dem Nachnamen-Index hinzuf\u00fcgen.<\/p>\n<p>Wenn Sie im Personenbereich der Suchleiste oder in der intelligenten Suche suchen oder eine Person hinzuf\u00fcgen, sucht Heredis nach bestehenden Personen mit diesem Nachnamen, auch wenn es sich um einen Namen handelt, der im Reiter <strong>Weitere Namen<\/strong> hinterlegt wurde.<\/p>\n<h3>Einen zusammengesetzten Nachnamen eingeben<\/h3>\n<p>Des Weiteren gibt es zusammengesetzte Nachnamen.<\/p>\n<p>Heredis erm\u00f6glicht es, zusammengesetzte Nachamen zu verwalten. Sie k\u00f6nnen diese mit oder ohne Bindestrich angeben.<\/p>\n<p>Geben Sie z. B. Schmidt-Berger ein.<\/p>\n<p>Heredis verwaltet diesen zusammengesetzten Namen als einen einzigen Nachnamen. Entsprechend finden Sie auch nur einen Eintrag im Nachnamen-Index.<\/p>\n<h3>Mehrere Nachnamen eingeben<\/h3>\n<p>Vor allem im spanischsprachigen Raum, aber in j\u00fcngerer Zeit auch in anderen L\u00e4ndern, ist es m\u00f6glich bzw. \u00fcblich mehrere Nachnamen zu tragen. So kann es vorkommen, dass eine Person sowohl den Nachamen des Vaters und den der Mutter tr\u00e4gt. Es handelt sich dabei nicht immer um einen zusammengesetzten Namen.<\/p>\n<p>Seit Heredis 2026 ist es m\u00f6glich, mehrere Nachnamen einzugeben.<br \/>\nGeben Sie den ersten Nachnamen ein und trennen Sie ihn mit einem Schr\u00e4gstrich \/ vom zweiten Nachnamen.<\/p>\n<p>Zum Beispiel: Martinez\/Gomes.<\/p>\n<p>Sie k\u00f6nnen die Nachnamen mit oder ohne Leerzeichen zwischen dem \/ und dem jeweiligen Nachnamen eingeben. Heredis wird sie formatieren.<br \/>\nIn dem Eingabefeld wird der Schr\u00e4gstrich sichtbar sein, an anderen Stellen jedoch nicht.<\/p>\n<p>Heredis betrachtet die beiden Nachnamen als zwei verschiedene Familiennamen. Das bedeutet, dass es zwei Eintr\u00e4ge im Nachnamen-Index gibt.<\/p>\n<p><strong>Hinweis<\/strong>: Unabh\u00e4ngig vom eingegebenen Format besteht ein Nachname aus Buchstaben mit oder ohne Umlauten. F\u00fcgen Sie keine Sonderzeichen (Klammern, Satzzeichen usw.) hinzu. Nur der Bindestrich kann in einem Nachnamen enthalten sein. F\u00fcgen Sie auch keine Bilder, Emojis usw. hinzu. Dies w\u00fcrden die Suchfunktionen st\u00f6ren und k\u00f6nnten zu Problemen beim GEDCOM-Export f\u00fchren.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Heredis erm\u00f6glicht die Eingabe einer Vielzahl von Daten. [&#8230;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129,131],"tags":[],"class_list":["post-54944","post","type-post","status-publish","format-standard","hentry","category-neuheiten","category-heredis-anwenden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Heredis erm\u00f6glicht die Eingabe einer Vielzahl von Daten. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-02T12:00:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T15:04:12+00:00\" \/>\n<meta name=\"author\" content=\"Helene Debacq\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Helene Debacq\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/\"},\"author\":{\"name\":\"Helene Debacq\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\"},\"headline\":\"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben\",\"datePublished\":\"2025-09-02T12:00:51+00:00\",\"dateModified\":\"2025-11-13T15:04:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/\"},\"wordCount\":497,\"articleSection\":[\"Neuheiten\",\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/\",\"name\":\"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"datePublished\":\"2025-09-02T12:00:51+00:00\",\"dateModified\":\"2025-11-13T15:04:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/00d7af69d95b497d8b3ca4b1ef4e66e0\",\"name\":\"Helene Debacq\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/helene-debacqheredis-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/","og_locale":"de_DE","og_type":"article","og_title":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase","og_description":"Heredis erm\u00f6glicht die Eingabe einer Vielzahl von Daten. [...]","og_url":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2025-09-02T12:00:51+00:00","article_modified_time":"2025-11-13T15:04:12+00:00","author":"Helene Debacq","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Helene Debacq","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/"},"author":{"name":"Helene Debacq","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0"},"headline":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben","datePublished":"2025-09-02T12:00:51+00:00","dateModified":"2025-11-13T15:04:12+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/"},"wordCount":497,"articleSection":["Neuheiten","Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/","url":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/","name":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"datePublished":"2025-09-02T12:00:51+00:00","dateModified":"2025-11-13T15:04:12+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/00d7af69d95b497d8b3ca4b1ef4e66e0","name":"Helene Debacq","url":"https:\/\/help.heredis.com\/de\/author\/helene-debacqheredis-com\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/54944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=54944"}],"version-history":[{"count":8,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/54944\/revisions"}],"predecessor-version":[{"id":55864,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/54944\/revisions\/55864"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=54944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=54944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=54944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}