{"id":50020,"date":"2022-12-11T18:58:26","date_gmt":"2022-12-11T17:58:26","guid":{"rendered":"https:\/\/help.heredis.com\/?p=50020"},"modified":"2024-11-03T23:53:32","modified_gmt":"2024-11-03T22:53:32","slug":"android-in-einer-genealogie-navigieren-eine-person-suchen","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/","title":{"rendered":"(Android) In einer Genealogie navigieren\/eine Person suchen"},"content":{"rendered":"<p>Mit Heredis f\u00fcr Android k\u00f6nnen Sie in einer Datei enthaltene genealogische Informationen aufrufen und bearbeiten.<\/p>\n<p>W\u00e4hlen Sie die Genealogie aus, die Sie aufrufen bzw. bearbeiten m\u00f6chten. Wenn mehrere Genealogie-Dateien in Ihrer Heredis-App verf\u00fcgbar sind, lesen Sie den Artikel <a href=\"https:\/\/help.heredis.com\/de\/android-von-einer-genealogie-zu-einer-anderen-wechseln\/\">(Android) Von einer Genealogie zu einer anderen wechseln<\/a>.<\/p>\n<p>\u00d6ffnen Sie die gew\u00fcnschte Person als Ausgangsperson (mittig auf dem Bildschirm) und sehen Sie sich ihre Informationen an bzw. bearbeiten diese.<\/p>\n<p>Sie haben daf\u00fcr mehrere M\u00f6glichkeiten:<\/p>\n<ul>\n<li>W\u00e4hlen Sie die Person in der Registerkarte <strong>Personen<\/strong> aus, der die Anzahl der in der Genealogie enthaltenen Personen vorangestellt ist.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-50022\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg\" alt=\"\" width=\"357\" height=\"773\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg 720w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de-138x300.jpg 138w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de-473x1024.jpg 473w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de-709x1536.jpg 709w\" sizes=\"(max-width: 357px) 100vw, 357px\" \/><\/p>\n<ul>\n<li>Sie k\u00f6nnen bequem von einer Person zur anderen wechseln, indem Sie die Ansicht <strong>Unmittelbare Familie<\/strong> aufrufen. Wenn Sie zum Beispiel den Urgro\u00dfvater v\u00e4terlicherseits des Probanden anzeigen lassen m\u00f6chten, tippen Sie auf das Feld des Gro\u00dfvaters v\u00e4terlicherseits und schlie\u00dflich auf das Feld seines Vaters.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-50025\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/noyau_familial_android_de.jpg\" alt=\"\" width=\"364\" height=\"789\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/noyau_familial_android_de.jpg 720w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/noyau_familial_android_de-138x300.jpg 138w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/noyau_familial_android_de-473x1024.jpg 473w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/noyau_familial_android_de-709x1536.jpg 709w\" sizes=\"(max-width: 364px) 100vw, 364px\" \/><\/p>\n<ul>\n<li>Suchen Sie <strong>Nach Kekule-Nummer<\/strong> oder <strong>Nach Benutzer-Referenznummer:<\/strong>\u00a0Tippen Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-48091\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/07\/bouton_points.png\" alt=\"\" width=\"19\" height=\"29\" \/> oben rechts und dann auf <strong>Suche <\/strong>in der Liste. W\u00e4hlen Sie die gew\u00fcnschte Nummernsuche aus und geben Sie die Nummer der gesuchten Person ein. Best\u00e4tigen Sie beim Tippen auf der Lupe oder OK (je nach Ger\u00e4t).<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-50031\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_android_de.jpg\" alt=\"\" width=\"377\" height=\"817\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_android_de.jpg 720w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_android_de-138x300.jpg 138w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_android_de-473x1024.jpg 473w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_android_de-709x1536.jpg 709w\" sizes=\"(max-width: 377px) 100vw, 377px\" \/><\/p>\n<ul>\n<li>Suchen Sie die Person mithilfe ihres Nachnamens und Vornamens. In der Registerkarte <strong>Personen<\/strong> k\u00f6nnen Sie im Feld Nachname den Familiennamen oder die ersten Buchstaben davon eingeben; bei Bedarf ebenso beim Vornamen. Die Liste aktualisiert sich automatisch.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-50028\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_indi_android_de.jpg\" alt=\"\" width=\"378\" height=\"819\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_indi_android_de.jpg 720w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_indi_android_de-138x300.jpg 138w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_indi_android_de-473x1024.jpg 473w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/rechercher_indi_android_de-709x1536.jpg 709w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/><\/p>\n<ul>\n<li>Navigieren Sie zu einer Person \u00fcber die Registerkarte <strong>Details der Person<\/strong>, zu deren Familie \u00fcber die Registerkarte <strong>Unmittelbare Familie. <\/strong>Sie k\u00f6nnen sie im dynamischen Stammbaum bis zu 3 Generationen \u00fcber die Registerkarte <strong>Dynamischer Baum<\/strong> anzeigen lassen.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone wp-image-50034\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/arbre_dynamique_android_de.jpg\" alt=\"\" width=\"411\" height=\"891\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/arbre_dynamique_android_de.jpg 720w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/arbre_dynamique_android_de-138x300.jpg 138w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/arbre_dynamique_android_de-473x1024.jpg 473w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/arbre_dynamique_android_de-709x1536.jpg 709w\" sizes=\"(max-width: 411px) 100vw, 411px\" \/><\/p>\n<p>Wenn Sie die Informationen zu einer Person \u00e4ndern m\u00f6chten, lesen Sie den Artikel <a href=\"https:\/\/help.heredis.com\/de\/android-eine-person-bearbeiten\/#\">(Android) Eine Person bearbeiten<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Heredis f\u00fcr Android k\u00f6nnen Sie in einer Datei enthaltene genealogische Informationen aufrufen und bearbeiten.<\/p>\n<p>W\u00e4hlen Sie die Genealogie aus [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147],"tags":[],"class_list":["post-50020","post","type-post","status-publish","format-standard","hentry","category-ios-android"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(Android) In einer Genealogie navigieren\/eine Person suchen - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Android) In einer Genealogie navigieren\/eine Person suchen - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Mit Heredis f\u00fcr Android k\u00f6nnen Sie in einer Datei enthaltene genealogische Informationen aufrufen und bearbeiten.  W\u00e4hlen Sie die Genealogie aus [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-11T17:58:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-03T22:53:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg\" \/>\n<meta name=\"author\" content=\"Sandra Clavier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Clavier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/\"},\"author\":{\"name\":\"Sandra Clavier\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\"},\"headline\":\"(Android) In einer Genealogie navigieren\\\/eine Person suchen\",\"datePublished\":\"2022-12-11T17:58:26+00:00\",\"dateModified\":\"2024-11-03T22:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/\"},\"wordCount\":302,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/liste_indi_android_de.jpg\",\"articleSection\":[\"Heredis-Apps iOS und Android\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/\",\"name\":\"(Android) In einer Genealogie navigieren\\\/eine Person suchen - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/liste_indi_android_de.jpg\",\"datePublished\":\"2022-12-11T17:58:26+00:00\",\"dateModified\":\"2024-11-03T22:53:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/liste_indi_android_de.jpg\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/liste_indi_android_de.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/android-in-einer-genealogie-navigieren-eine-person-suchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Android) In einer Genealogie navigieren\\\/eine Person suchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\",\"name\":\"Sandra Clavier\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/sandra-clavierheredis-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Android) In einer Genealogie navigieren\/eine Person suchen - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/","og_locale":"de_DE","og_type":"article","og_title":"(Android) In einer Genealogie navigieren\/eine Person suchen - Heredis Help Knowledgebase","og_description":"Mit Heredis f\u00fcr Android k\u00f6nnen Sie in einer Datei enthaltene genealogische Informationen aufrufen und bearbeiten.  W\u00e4hlen Sie die Genealogie aus [...]","og_url":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2022-12-11T17:58:26+00:00","article_modified_time":"2024-11-03T22:53:32+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg","type":"","width":"","height":""}],"author":"Sandra Clavier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sandra Clavier","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/"},"author":{"name":"Sandra Clavier","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d"},"headline":"(Android) In einer Genealogie navigieren\/eine Person suchen","datePublished":"2022-12-11T17:58:26+00:00","dateModified":"2024-11-03T22:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/"},"wordCount":302,"image":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg","articleSection":["Heredis-Apps iOS und Android"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/","url":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/","name":"(Android) In einer Genealogie navigieren\/eine Person suchen - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg","datePublished":"2022-12-11T17:58:26+00:00","dateModified":"2024-11-03T22:53:32+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/liste_indi_android_de.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/android-in-einer-genealogie-navigieren-eine-person-suchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"(Android) In einer Genealogie navigieren\/eine Person suchen"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d","name":"Sandra Clavier","url":"https:\/\/help.heredis.com\/de\/author\/sandra-clavierheredis-com\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/50020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=50020"}],"version-history":[{"count":5,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/50020\/revisions"}],"predecessor-version":[{"id":54576,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/50020\/revisions\/54576"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=50020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=50020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=50020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}