{"id":49968,"date":"2022-12-10T21:36:10","date_gmt":"2022-12-10T20:36:10","guid":{"rendered":"https:\/\/help.heredis.com\/?p=49968"},"modified":"2022-12-10T21:36:10","modified_gmt":"2022-12-10T20:36:10","slug":"ios-von-einer-genealogie-zu-einer-anderen-wechseln","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/","title":{"rendered":"(iOS) Von einer Genealogie zu einer anderen wechseln"},"content":{"rendered":"<p>Sie k\u00f6nnen in Heredis f\u00fcr iOS ebenso wie in Heredis f\u00fcr Windows oder Mac mehrere Genealogien nutzen.<\/p>\n<p>Legen Sie eine neue Datei an oder nutzen Sie eine Datei von Ihrem Computer und wechseln Sie bequem zwischen den Genealogien:<br \/>\n\u2022 Tippen Sie auf den Button <img decoding=\"async\" class=\"alignnone  wp-image-48049\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg\" alt=\"\" width=\"28\" height=\"27\" \/> .<br \/>\n\u2022 Tippen Sie auf den Namen der obersten Datei.<br \/>\n\u2022 W\u00e4hlen Sie die gew\u00fcnschte Genealogie aus.<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-49969\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/Menu-iOS-DE.png\" alt=\"\" width=\"410\" height=\"729\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/Menu-iOS-DE.png 750w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/Menu-iOS-DE-169x300.png 169w, https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/12\/Menu-iOS-DE-576x1024.png 576w\" sizes=\"(max-width: 410px) 100vw, 410px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie k\u00f6nnen in Heredis f\u00fcr iOS ebenso wie in Heredis f\u00fcr Windows oder Mac mehrere Genealogien nutzen.<\/p>\n<p>Legen Sie eine [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147],"tags":[],"class_list":["post-49968","post","type-post","status-publish","format-standard","hentry","category-ios-android"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Sie k\u00f6nnen in Heredis f\u00fcr iOS ebenso wie in Heredis f\u00fcr Windows oder Mac mehrere Genealogien nutzen.  Legen Sie eine [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-10T20:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg\" \/>\n<meta name=\"author\" content=\"Sandra Clavier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sandra Clavier\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/\"},\"author\":{\"name\":\"Sandra Clavier\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\"},\"headline\":\"(iOS) Von einer Genealogie zu einer anderen wechseln\",\"datePublished\":\"2022-12-10T20:36:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/\"},\"wordCount\":70,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bouton_menu_android_fr.jpg\",\"articleSection\":[\"Heredis-Apps iOS und Android\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/\",\"name\":\"(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bouton_menu_android_fr.jpg\",\"datePublished\":\"2022-12-10T20:36:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bouton_menu_android_fr.jpg\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/bouton_menu_android_fr.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(iOS) Von einer Genealogie zu einer anderen wechseln\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/999bf6771565c2d9d42d51d0913b2a6d\",\"name\":\"Sandra Clavier\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/sandra-clavierheredis-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/","og_locale":"de_DE","og_type":"article","og_title":"(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase","og_description":"Sie k\u00f6nnen in Heredis f\u00fcr iOS ebenso wie in Heredis f\u00fcr Windows oder Mac mehrere Genealogien nutzen.  Legen Sie eine [...]","og_url":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2022-12-10T20:36:10+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg","type":"","width":"","height":""}],"author":"Sandra Clavier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sandra Clavier"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/"},"author":{"name":"Sandra Clavier","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d"},"headline":"(iOS) Von einer Genealogie zu einer anderen wechseln","datePublished":"2022-12-10T20:36:10+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/"},"wordCount":70,"image":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg","articleSection":["Heredis-Apps iOS und Android"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/","url":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/","name":"(iOS) Von einer Genealogie zu einer anderen wechseln - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg","datePublished":"2022-12-10T20:36:10+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2022\/09\/bouton_menu_android_fr.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/ios-von-einer-genealogie-zu-einer-anderen-wechseln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"(iOS) Von einer Genealogie zu einer anderen wechseln"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/999bf6771565c2d9d42d51d0913b2a6d","name":"Sandra Clavier","url":"https:\/\/help.heredis.com\/de\/author\/sandra-clavierheredis-com\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/49968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=49968"}],"version-history":[{"count":1,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/49968\/revisions"}],"predecessor-version":[{"id":49972,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/49968\/revisions\/49972"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=49968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=49968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=49968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}