{"id":20752,"date":"2020-09-22T09:00:36","date_gmt":"2020-09-22T07:00:36","guid":{"rendered":"https:\/\/help.heredis.com\/find-relationships-2\/"},"modified":"2020-11-05T23:30:13","modified_gmt":"2020-11-05T22:30:13","slug":"verbindungen-suchen","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/","title":{"rendered":"Verbindungen suchen"},"content":{"rendered":"<p>Die Funktion <strong>Verbindungen suchen<\/strong> analysiert alle Verbindungen in Ihrer Genealogie-Datei, um die Art der Verbindung zwischen zwei Personen klar zu machen, selbst wenn diese nicht direkt verwandt oder verschw\u00e4gert sind.<\/p>\n<ul>\n<li>Klicken Sie in der Men\u00fcleiste auf <strong>Suchen<\/strong> &gt; <strong>Verbindungen suchen<\/strong><\/li>\n<li>oder klicken Sie in der Symbolleiste auf den Button<img decoding=\"async\" class=\"alignnone wp-image-1940\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png\" alt=\"\" width=\"25\" height=\"25\" \/> und dann <img decoding=\"async\" class=\"alignnone wp-image-1670\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/40-Rechercher_liens.png\" alt=\"\" width=\"25\" height=\"25\" \/>.<\/li>\n<\/ul>\n<p>Standardm\u00e4\u00dfig wird die prim\u00e4re Person als erste von der Analyse betreffende Person angezeigt. Wenn Sie auf die Lupe <img decoding=\"async\" class=\"alignnone size-full wp-image-9928\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/06\/16-loupe2.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> klicken, k\u00f6nnen Sie das \u00e4ndern.<\/p>\n<p>W\u00e4hlen Sie dann mit der Lupe <img decoding=\"async\" class=\"alignnone size-full wp-image-9928\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/06\/16-loupe2.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> die zweite Person in der angezeigten Liste aus. Ab Heredis 2021 <img decoding=\"async\" class=\"alignnone wp-image-18030\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/06\/HeredisIcon.png\" alt=\"\" width=\"20\" height=\"20\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/06\/HeredisIcon.png 256w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/06\/HeredisIcon-150x150.png 150w\" sizes=\"(max-width: 20px) 100vw, 20px\" \/>, klicken Sie auf den Button <strong>Proband<\/strong> oder <strong>Prim\u00e4re Person<\/strong> f\u00fcr eine schnellere Auswahl. Klicken Sie auf den Button <strong>Suchen<\/strong>, um die Suche nach Verbindungen zu starten.<\/p>\n<p><em>Windows: Verbindungen suchen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-20770\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipWindows_DE-2.png\" alt=\"\" width=\"915\" height=\"534\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipWindows_DE-2.png 1062w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipWindows_DE-2-300x175.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipWindows_DE-2-1024x598.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipWindows_DE-2-768x448.png 768w\" sizes=\"(max-width: 915px) 100vw, 915px\" \/><\/p>\n<p><em>Mac: Verbindungen suchen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-20773\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipMac_DE.png\" alt=\"\" width=\"906\" height=\"545\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipMac_DE.png 986w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipMac_DE-300x180.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchRelationshipMac_DE-768x462.png 768w\" sizes=\"(max-width: 906px) 100vw, 906px\" \/><\/p>\n<hr \/>\n<h3 class=\"p1\">Gemeinsame Vorfahren<\/h3>\n<p>In den <strong>Suchergebnissen<\/strong> sucht Heredis nach eventuellen gemeinsamen Vorfahren. Wenn Sie einen der gefundenen gemeinsamen Vorfahren anklicken, zeigt Ihnen eine Tabelle an, \u00fcber welche Wege die beiden Personen mit diesem Vorfahren verbunden sind.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-20776\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/CommonAncestorRelationshipWindows_DE.png\" alt=\"\" width=\"901\" height=\"526\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/CommonAncestorRelationshipWindows_DE.png 1062w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/CommonAncestorRelationshipWindows_DE-300x175.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/CommonAncestorRelationshipWindows_DE-1024x598.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/CommonAncestorRelationshipWindows_DE-768x448.png 768w\" sizes=\"(max-width: 901px) 100vw, 901px\" \/><\/p>\n<p class=\"p1\">Bei Implex wegen Eheschlie\u00dfungen zwischen Blutsverwandten kann eine Person \u00fcber mehrere Wege mit dem gemeinsamen Vorfahren verbunden sein. Die Anzahl der Wege wird oben in der Spalte angezeigt. Klicken Sie auf die Zeilen der verschiedenen Verbindungen, um die Verwandtschaftsgrade zwischen diesen Personen hervorzuheben.<\/p>\n<hr \/>\n<h3>Andere Verwandtschaftsbeziehungen<\/h3>\n<p>Heredis pr\u00fcft nun, ob die Personen verwandt oder verschw\u00e4gert sind: Urgro\u00dfonkel m\u00fctterlicherseits, Schwager des Schwiegersohns, Partner einer Cousine zweiten Grades.<\/p>\n<p>W\u00e4hlen Sie die Verbindung oder eine andere Person in der Dropdown-Liste. Die Tabelle zeigt an, wie zwei Personen miteinander verwandt oder verschw\u00e4gert sind. Jede Verbindung wird erkl\u00e4rt. Um die Verbindung leichter nachzuvollziehen, k\u00f6nnen Sie \u00fcber den Button <img decoding=\"async\" class=\"alignnone wp-image-17273\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/05\/75-SensLecture.png\" alt=\"\" width=\"20\" height=\"20\" \/> die Leserichtung \u00e4ndern.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-20779\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchResultRelationship_DE.png\" alt=\"\" width=\"293\" height=\"459\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchResultRelationship_DE.png 347w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/09\/SearchResultRelationship_DE-192x300.png 192w\" sizes=\"(max-width: 293px) 100vw, 293px\" \/><\/p>\n<p>Durch Klicken auf den Button <img decoding=\"async\" class=\"alignnone wp-image-426\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/imprimer.png\" alt=\"\" width=\"25\" height=\"25\" \/>\u00a0k\u00f6nnen Sie alle Tabellen ausdrucken.<\/p>\n<hr \/>\n<h3>Andere Verbindungen<\/h3>\n<p class=\"p1\">Zuletzt sucht Heredis nach allen nicht-verwandtschaftlichen Verbindungen: Gibt es unter diesen Verbindungen eine Person, die Zeuge einer Hochzeit oder eines Todes war?<\/p>\n<p class=\"p1\">Die Verbindung wird in Form einer Tabelle dargestellt, in der in jeder Zeile die Verbindung erkl\u00e4rt wird: Sohn von, Mutter von, Zeuge eines Todes etc. Dies erleichtert die Suche nach der Verbindung zwischen diesen beiden Personen.<\/p>\n<p class=\"p1\">Was die Verwandten anbelangt, klicken Sie eventuell auf den Button <img decoding=\"async\" class=\"alignnone wp-image-17273\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/05\/75-SensLecture.png\" alt=\"\" width=\"20\" height=\"20\" \/> (Leserichtung \u00e4ndern), um die Verbindung besser nachzuvollziehen.<\/p>\n<p class=\"p1\">Klicken Sie auf eine beliebige Person, um deren Zusammenfassung auf der rechten Seite des Bildschirms <strong>Verbindungen suchen<\/strong> anzusehen.<\/p>\n<p class=\"p1\">\u00dcber den Button <img decoding=\"async\" class=\"alignnone wp-image-426\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/imprimer.png\" alt=\"\" width=\"25\" height=\"25\" \/> starten Sie Ihr Textverarbeitungsprogramm und k\u00f6nnen die Details der gew\u00e4hlten Verbindung sowie die Zusammenfassung aller gefundenen Verbindungen ausdrucken.<\/p>\n<hr \/>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>Die Funktion Verbindungen suchen analysiert alle Verbindungen in Ihrer Genealogie-Datei, um die Art der Verbindung zwischen zwei Personen klar zu [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[],"class_list":["post-20752","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verbindungen suchen - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verbindungen suchen - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Die Funktion Verbindungen suchen analysiert alle Verbindungen in Ihrer Genealogie-Datei, um die Art der Verbindung zwischen zwei Personen klar zu [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T07:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T22:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Verbindungen suchen\",\"datePublished\":\"2020-09-22T07:00:36+00:00\",\"dateModified\":\"2020-11-05T22:30:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/\"},\"wordCount\":411,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/recherche.png\",\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/\",\"name\":\"Verbindungen suchen - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/recherche.png\",\"datePublished\":\"2020-09-22T07:00:36+00:00\",\"dateModified\":\"2020-11-05T22:30:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/recherche.png\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/recherche.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/verbindungen-suchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verbindungen suchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verbindungen suchen - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/","og_locale":"de_DE","og_type":"article","og_title":"Verbindungen suchen - Heredis Help Knowledgebase","og_description":"Die Funktion Verbindungen suchen analysiert alle Verbindungen in Ihrer Genealogie-Datei, um die Art der Verbindung zwischen zwei Personen klar zu [...]","og_url":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2020-09-22T07:00:36+00:00","article_modified_time":"2020-11-05T22:30:13+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png","type":"","width":"","height":""}],"author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Verbindungen suchen","datePublished":"2020-09-22T07:00:36+00:00","dateModified":"2020-11-05T22:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/"},"wordCount":411,"image":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png","articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/","url":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/","name":"Verbindungen suchen - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png","datePublished":"2020-09-22T07:00:36+00:00","dateModified":"2020-11-05T22:30:13+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/verbindungen-suchen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/recherche.png"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/verbindungen-suchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Verbindungen suchen"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/20752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=20752"}],"version-history":[{"count":4,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/20752\/revisions"}],"predecessor-version":[{"id":21511,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/20752\/revisions\/21511"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=20752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=20752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=20752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}