{"id":18331,"date":"2020-04-30T15:51:27","date_gmt":"2020-04-30T13:51:27","guid":{"rendered":"https:\/\/help.heredis.com\/le-dictionnaire-des-sources\/"},"modified":"2022-01-25T14:30:35","modified_gmt":"2022-01-25T13:30:35","slug":"quellen-index","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/quellen-index\/","title":{"rendered":"Quellen-Index"},"content":{"rendered":"<div class=\"page\" title=\"Page 265\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<div class=\"page\" title=\"Page 265\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Der <strong>Quellen-Index<\/strong> gruppiert alle Quellen, die mit einem oder mehreren Ereignissen, Personen oder pers\u00f6nlichen Fakten Ihrer Genealogie-Datei verkn\u00fcpft sind.<\/p>\n<p>Um alle in Ihrer Genealogie-Datei eingegebenen Quellen zu verwalten, w\u00e4hlen Sie \u00fcber die Men\u00fcleiste <strong>Werkzeuge &gt; Quellen-Index<\/strong>.<\/p>\n<p>Neue Quellen k\u00f6nnen ebenfalls \u00fcber die Funktion <strong>Datenerfassung aus Volksz\u00e4hlungen<\/strong> oder direkt im <strong>Quellen-Index<\/strong> eingegeben werden. Eine andere M\u00f6glichkeit ist, Quellen aus einer anderen Datei zu importieren und nachtr\u00e4glich zuzuordnen. Mehr Informationen zur Erstellung einer Quelle erhalten Sie im Artikel <a href=\"https:\/\/help.heredis.com\/de\/quellen\/\">Quellen<\/a>.<\/p>\n<p>Lesen Sie ebenfalls den Artikel <a href=\"https:\/\/help.heredis.com\/de\/indizes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Indizes<\/a>, um einen allgemeinen \u00dcberblick \u00fcber die M\u00f6glichkeiten, die Ihnen die Indizes bieten, zu erhalten.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3>Den Quellen-Index \u00f6ffnen<\/h3>\n<p>\u00d6ffnen Sie den <strong>Quellen-Index:<\/strong><\/p>\n<ul>\n<li>\u00fcber das Men\u00fc <strong>Werkzeuge<\/strong> in der Men\u00fcleiste,<\/li>\n<li>indem Sie in der Symbolleiste den Button <img decoding=\"async\" class=\"alignnone wp-image-18453\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png\" alt=\"\" width=\"26\" height=\"29\" \/> und dann den Button\u00a0 <img decoding=\"async\" class=\"alignnone wp-image-1881\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/dicoSources.png\" alt=\"\" width=\"25\" height=\"25\" \/>ausw\u00e4hlen,<\/li>\n<li>oder<strong> (Mac)<\/strong> auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-17572\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/BookSymbolMac_DE.png\" alt=\"\" width=\"20\" height=\"19\" \/> im Themenbereich <strong>Quellen <\/strong>der Suchleiste klicken.<\/li>\n<\/ul>\n<p><em>Windows: Quellen-Index<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-15060\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Source-Index_DE.jpg\" alt=\"\" width=\"1045\" height=\"771\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Source-Index_DE.jpg 1045w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Source-Index_DE-300x221.jpg 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Source-Index_DE-1024x756.jpg 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Source-Index_DE-768x567.jpg 768w\" sizes=\"(max-width: 1045px) 100vw, 1045px\" \/><\/p>\n<p><em>Mac: Quellen-Index<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-16566\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE.png\" alt=\"\" width=\"2426\" height=\"1344\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE.png 2426w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE-300x166.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE-1024x567.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE-768x425.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE-1536x851.png 1536w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/SourceIndexMac_DE-1920x1064.png 1920w\" sizes=\"(max-width: 2426px) 100vw, 2426px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Eine Quelle duplizieren<\/h3>\n<p>Sparen Sie Zeit und duplizieren Sie einfach eine Quelle, wenn Sie z. B. die Signatur \u00e4ndern wollen.<\/p>\n<ul>\n<li>W\u00e4hlen Sie die zu duplizierende Quelle aus.<\/li>\n<li>Klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-13780\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/12\/16-copier.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> in der Aktionsleiste unterhalb der aufgelisteten Quellen.<\/li>\n<li>Bearbeiten Sie die duplizierte Quelle. Sie hat noch keine Verwendung.<\/li>\n<li>\u00c4ndern Sie sie oder Ihre Details, um eine neue Quelle zu erhalten.<\/li>\n<\/ul>\n<h3>Eine Quelle suchen<\/h3>\n<p>Geben Sie im Suchfeld ein Wort ein, dass in einem der Eingabefelder der gesuchten Quelle vorkommt.<\/p>\n<p>Die Anzahl der gefundenen Elemente wird unter dem Suchfeld angezeigt.<\/p>\n<p><strong>(Mac)<\/strong> Klicken Sie auf die <strong>Lupe<\/strong> und w\u00e4hlen Sie den Suchmodus: <strong>Enth\u00e4lt<\/strong> das eingegebene Wort oder <strong>Beginnt mit<\/strong> den eingegebenen Buchstaben.<\/p>\n<p>Um eine Suche nach einem Begriff zu beenden, klicken Sie auf <strong>(Windows)<\/strong> <img decoding=\"async\" class=\"size-full wp-image-1465 alignnone\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-gomme.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>; <strong>(Mac)<\/strong> <img decoding=\"async\" class=\"size-full wp-image-1466 alignnone\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/Gomme_16.png\" alt=\"\" width=\"16\" height=\"16\" \/> rechts neben dem Suchfeld.<\/p>\n<p>Konsultieren Sie die Liste der Verwendungen der gew\u00e4hlten Quelle im unteren Teil des Fensters.<\/p>\n<div class=\"page\" title=\"Page 267\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Um einen gespeicherte Quelle im<strong> Quellen-Index<\/strong> wiederzufinden:<\/p>\n<ul>\n<li>Klicken Sie direkt auf die Quelle in der angezeigten Liste.<br \/>\nOder verwenden Sie die Pfeiltasten auf Ihrer Tastatur, um zu der gew\u00fcnschten Quelle zu gelangen.<br \/>\nOder geben Sie die Anfangsbuchstabens eines Merkmals der Quelle in das Suchfeld ein. Sie k\u00f6nnen eine Quelle nach ihrem Titel, Herkunft, Signatur usw. recherchieren.<\/li>\n<\/ul>\n<p>Sie k\u00f6nnen die Liste der angezeigten Quellen verfeinern:<\/p>\n<ul>\n<li>Um die Liste auf ungenutzte Quellen zu beschr\u00e4nken, aktivieren Sie das entsprechende Kontrollk\u00e4stchen.<\/li>\n<li><strong>(Windows)<\/strong> Um sich nur als privat deklarierte Quellen anzeigen zu lassen, aktivieren Sie das entsprechende Kontrollk\u00e4stchen.<\/li>\n<li>Klicken Sie in den Kopf einer Spalte, um sich die gespeicherten Quellen in alphabetischer Reihenfolge bzw. Zahlenfolge f\u00fcr die Rubriken Titel, Archiv, Dokument, Bestandsnr.\/Signatur, Medienart oder Ablage anzeigen zu lassen. Ein erneuter Klick auf den Spaltenkopf dreht die angezeigte Reihenfolge wieder um. In der Spalte, \u00fcber die die Reihenfolge\/Anordnung bestimmt wurde, erscheint ein Pfeil. Die Spalten N, T, M, P erm\u00f6glichen Ihnen die Quellen danach zu ordnen, ob Sie eine Notiz, eine Transkription, ein Medium haben oder als privat markiert wurden.\u00a0 Klicken Sie auf den Kopf dieser Spalten und ordnen Sie die Quellen so, wie es Ihnen am besten passt.<\/li>\n<\/ul>\n<p>Sobald Sie eine Quelle in der Liste ausgew\u00e4hlt haben, erscheinen deren Details (Titel, Archiv, Dokument, private Quelle, &#8230;) in der rechten Spalte im Fenster des Indexes.<\/p>\n<p>(<strong>Mac<\/strong>) Sie k\u00f6nnen die Detailfelder der ausgew\u00e4hlten Quelle direkt \u00fcber die rechte Spalte bearbeiten.<\/p>\n<p>Die Verwendungen der ausgew\u00e4hlten Quelle werden unter der Liste der Quellen angezeigt.<\/p>\n<p><em>Windows: Verwendungen einer Quelle<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-21888\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexWindows_DE.png\" alt=\"\" width=\"858\" height=\"129\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexWindows_DE.png 858w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexWindows_DE-300x45.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexWindows_DE-768x115.png 768w\" sizes=\"(max-width: 858px) 100vw, 858px\" \/><\/p>\n<p><em>Mac: Verwendungen einer Quelle<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-21891\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexMac_DE.png\" alt=\"\" width=\"1003\" height=\"130\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexMac_DE.png 1003w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexMac_DE-300x39.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/SourcesIndexMac_DE-768x100.png 768w\" sizes=\"(max-width: 1003px) 100vw, 1003px\" \/><\/p>\n<p>Doppelklicken Sie auf einen Verwendungseintrag um direkt zu dem betreffenden Ereignis oder zu der betreffenden Person zu navigieren.<\/p>\n<p>Wenn Sie eine Quelle in der Liste des Indexes ausgew\u00e4hlt haben, k\u00f6nnen Sie diese l\u00f6schen oder bearbeiten. Ver\u00e4nderungen der Quelle werden auf alle ihre Verwendungen angewandt.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3>Eine Quelle durch eine andere ersetzen<\/h3>\n<p>Vielleicht haben Sie ja im <strong>Quellen-Index<\/strong> mehrere Quellen abgespeichert, die eigentlich identisch sind. Sie k\u00f6nnen dann eine einzige Quelle beibehalten, indem Sie eine Quelle durch die andere im Index ersetzen.<\/p>\n<ul>\n<li>W\u00e4hlen Sie zuerst die zu l\u00f6schende Quelle.<\/li>\n<li>Klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-8828\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/05\/16-remplacer.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>.<\/li>\n<li>W\u00e4hlen Sie dann die Quelle, die Sie behalten m\u00f6chten.<\/li>\n<li>Best\u00e4tigen Sie mit <strong>Ausw\u00e4hlen.<\/strong><\/li>\n<li>Best\u00e4tigen Sie den Vorgang, indem Sie auf den Button <strong>Ja<\/strong> klicken. Alle Personen\/Ereignisse, mit denen die urspr\u00fcngliche Quelle verkn\u00fcpft war, werden entsprechend aktualisiert.<\/li>\n<\/ul>\n<h3>Eine Quelle l\u00f6schen<\/h3>\n<p>W\u00e4hlen Sie die Quelle in der Liste der Quellen.<\/p>\n<ul>\n<li>Klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-11954\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/16-moins-1.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>.<br \/>\nHeredis zeigt an, wenn diese Quelle verwendet wird. Wenn Sie dem L\u00f6schen zustimmen, verschwindet die Quelle aus der Liste der Quellen f\u00fcr das Ereignis, dem sie zugeordnet wurden.<\/li>\n<\/ul>\n<h3>Ungenutzte Quellen l\u00f6schen<\/h3>\n<p>Um alle ungenutzten Quellen Ihrer Genealogie-Datei zu l\u00f6schen, w\u00e4hlen Sie die Option <strong>Alle ungenutzten Quellen l\u00f6schen<\/strong> \u00fcber <strong>(Windows)<\/strong> den Button <strong>Werkzeuge<\/strong>;<strong> (Mac)<\/strong> das Zahnrad<strong> Optionen <img decoding=\"async\" class=\"alignnone size-full wp-image-12076\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/roue-crantee.png\" alt=\"\" width=\"32\" height=\"32\" \/><\/strong>.<\/p>\n<h3>Mehrfachauswahl<\/h3>\n<p>Um mehrere Quellen gleichzeitig zu bearbeiten:<\/p>\n<ul>\n<li><strong>(Windows)<\/strong> Halten Sie die STRG- oder die Umschalttaste gedr\u00fcckt und klicken Sie auf die verschiedenen Quellen, die Sie einbeziehen m\u00f6chten.<\/li>\n<li><strong>(Mac)<\/strong> Halten Sie die Command- oder die Umschalttaste gedr\u00fcckt und klicken Sie auf die verschiedenen Quellen, die Sie einbeziehen m\u00f6chten.<\/li>\n<li>W\u00e4hlen Sie anschlie\u00dfend die gew\u00fcnschte Aktion aus: das L\u00f6schen, Ersetzen oder Drucken der gew\u00e4hlten Quellen.<\/li>\n<\/ul>\n<h3>Zwei Spalten austauschen<\/h3>\n<p>Diese Option erm\u00f6glicht Ihnen, den Inhalt von zwei Rubriken einfach auszutauschen.<\/p>\n<ul>\n<li>W\u00e4hlen Sie eine oder mehrere Quellen \u00fcber die Mehrfachauswahl.<\/li>\n<li><strong>(Windows)<\/strong> Klicken Sie auf den Button <strong>Werkzeuge &gt; Tabellenfelder austauschen<\/strong> und w\u00e4hlen Sie die beiden Rubriken, die Sie austauschen m\u00f6chten.<\/li>\n<li><strong>(Mac)<\/strong> Klicken Sie auf das Zahnrad <strong>Optionen<\/strong> <img decoding=\"async\" class=\"alignnone size-full wp-image-12076\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/roue-crantee.png\" alt=\"\" width=\"32\" height=\"32\" \/>. W\u00e4hlen Sie die Option <strong>Tabellenfelder austauschen <\/strong>und anschlie\u00dfend die beiden Rubriken, die Sie austauschen m\u00f6chten.<\/li>\n<\/ul>\n<h3>Den Inhalt \u00e4ndern<\/h3>\n<p>Sie k\u00f6nnen den Inhalt eines Feldes durch eine andere Option der ausgew\u00e4hlten Rubrik ersetzen:<\/p>\n<ul>\n<li>W\u00e4hlen Sie eine oder mehrere Quellen \u00fcber die Mehrfachauswahl aus.<\/li>\n<li><strong>(Windows)<\/strong> Klicken Sie auf den Button <strong>Werkzeuge &gt; \u00c4ndern Sie den Inhalt<\/strong> und w\u00e4hlen Sie die Rubrik aus, die Sie \u00e4ndern m\u00f6chten. W\u00e4hlen Sie anschlie\u00dfend den neuen Wert f\u00fcr diese Rubrik, den Sie einf\u00fcgen m\u00f6chten.<\/li>\n<li><strong>(Mac)<\/strong> Klicken Sie auf das Zahnrad <strong>Optionen<\/strong>. Klicken Sie anschlie\u00dfend auf <strong>\u00c4ndern Sie den Inhalt<\/strong> und w\u00e4hlen Sie die Rubrik aus, die Sie \u00e4ndern m\u00f6chten. W\u00e4hlen Sie anschlie\u00dfend den neuen Inhalt f\u00fcr diese Rubrik, den Sie einf\u00fcgen m\u00f6chten.<\/li>\n<\/ul>\n<p><strong>Hinweis<\/strong>: Vor der \u00dcbernahme der \u00c4nderungen zeigt Ihnen Heredis eine Best\u00e4tigungsnachricht mit der Anzahl der Quellen an, die von den gew\u00fcnschten \u00c4nderungen betroffen sind. Klicken Sie auf Ja, wenn Sie die \u00c4nderungen vornehmen m\u00f6chten, und Nein, wenn Sie die \u00c4nderungen nicht durchf\u00fchren m\u00f6chten.<\/p>\n<h3>(Windows) Die Drucken-Buttons<\/h3>\n<h4>Datenblatt einer Quelle drucken<\/h4>\n<p>Um das Datenblatt einer gew\u00e4hlten Quelle des Quellen-Indexes zu drucken, klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-9919\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/06\/16-imprimer.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> in der Aktionsleiste im Quellen-Index.<br \/>\nDas Datenblatt beinhaltet alle Rubriken der Quelle, ihre Verwendungen, das eingegebene Transkript sowie die der Quelle hinzugef\u00fcgten Bilder, wenn Sie diese anzeigen m\u00f6chten.<\/p>\n<h4>Index drucken<\/h4>\n<p>Der Button <strong>Drucken<\/strong> erstellt eine Liste aller Quellen, die in dem Index angezeigt werden.<br \/>\nWenn Sie vorher eine Recherche durchgef\u00fchrt haben, werden nur die Quellen in die Liste aufgenommen, die als Ergebnis angezeigt wurden. Heredis beh\u00e4lt ebenfalls die Reihenfolge, die Sie durch das Klicken in die entsprechenden Spalten der verschiedenen Rubriken ausgew\u00e4hlt haben, bei.<br \/>\nSie k\u00f6nnen ebenfalls eine Liste aller Quellen Ihrer Datei \u00fcber das Men\u00fc <strong>Berichte &gt; Benutzerdefinierte Listen &gt; Quellenlisten <\/strong>erstellen.<br \/>\nWenn Sie Ihre Arbeit im Quellen-Index abgeschlossen haben, k\u00f6nnen Sie das Fenster einfach \u00fcber den entsprechenden Button schlie\u00dfen und zur vorherigen Hauptansicht zur\u00fcckkommen.<\/p>\n<h3>Quellenlisten drucken<\/h3>\n<p><strong>(Mac)<\/strong> Klicken Sie auf das Zahnrad <strong>Optionen<\/strong>. W\u00e4hlen Sie Drucken und anschlie\u00dfend den Listentyp, den Sie ausdrucken m\u00f6chten.<\/p>\n<p><strong>(Windows)\u00a0<\/strong>Klicken Sie auf den Button <strong>Werkzeuge <\/strong><strong>&gt; Drucken <\/strong>und w\u00e4hlen Sie anschlie\u00dfend den Listentyp, den Sie ausdrucken m\u00f6chten.<\/p>\n<p>Weitere Informationen finden Sie in den Artikeln <a href=\"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Benutzerdefinierte Listen<\/a>, <a href=\"https:\/\/help.heredis.com\/de\/listen-erstellen-und-bearbeiten\/\" target=\"_blank\" rel=\"noopener noreferrer\">(Mac) Listen erstellen und bearbeiten<\/a>,\u00a0 <a href=\"https:\/\/help.heredis.com\/de\/windows-listenvorlagen\/\" target=\"_blank\" rel=\"noopener noreferrer\">(Windows) Listenvorlagen<\/a>.<\/p>\n<h3>Index von einer anderen Datei importieren<\/h3>\n<p>Heredis erm\u00f6glicht es Ihnen, einen Index von einer Datei in Ihre bestehende Datei zu importieren. Mehr Informationen finden Sie in dem Artikel:\u00a0<a href=\"https:\/\/help.heredis.com\/de\/importieren-eines-indexes-in-eine-heredis-datei\/\">Import von Indizes in eine Heredis-Datei.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Quellen-Index gruppiert alle Quellen, die mit einem oder mehreren Ereignissen, Personen oder pers\u00f6nlichen Fakten Ihrer Genealogie-Datei verkn\u00fcpft sind. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[],"class_list":["post-18331","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quellen-Index - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/quellen-index\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quellen-Index - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Der Quellen-Index gruppiert alle Quellen, die mit einem oder mehreren Ereignissen, Personen oder pers\u00f6nlichen Fakten Ihrer Genealogie-Datei verkn\u00fcpft sind. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/quellen-index\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-30T13:51:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-25T13:30:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Quellen-Index\",\"datePublished\":\"2020-04-30T13:51:27+00:00\",\"dateModified\":\"2022-01-25T13:30:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/\"},\"wordCount\":1350,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Button_Index.png\",\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/\",\"name\":\"Quellen-Index - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Button_Index.png\",\"datePublished\":\"2020-04-30T13:51:27+00:00\",\"dateModified\":\"2022-01-25T13:30:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Button_Index.png\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Button_Index.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/quellen-index\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quellen-Index\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quellen-Index - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/quellen-index\/","og_locale":"de_DE","og_type":"article","og_title":"Quellen-Index - Heredis Help Knowledgebase","og_description":"Der Quellen-Index gruppiert alle Quellen, die mit einem oder mehreren Ereignissen, Personen oder pers\u00f6nlichen Fakten Ihrer Genealogie-Datei verkn\u00fcpft sind. [...]","og_url":"https:\/\/help.heredis.com\/de\/quellen-index\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2020-04-30T13:51:27+00:00","article_modified_time":"2022-01-25T13:30:35+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png","type":"","width":"","height":""}],"author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Quellen-Index","datePublished":"2020-04-30T13:51:27+00:00","dateModified":"2022-01-25T13:30:35+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/"},"wordCount":1350,"image":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png","articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/quellen-index\/","url":"https:\/\/help.heredis.com\/de\/quellen-index\/","name":"Quellen-Index - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png","datePublished":"2020-04-30T13:51:27+00:00","dateModified":"2022-01-25T13:30:35+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/quellen-index\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/04\/Button_Index.png"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/quellen-index\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Quellen-Index"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/18331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=18331"}],"version-history":[{"count":27,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/18331\/revisions"}],"predecessor-version":[{"id":47311,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/18331\/revisions\/47311"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=18331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=18331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=18331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}