{"id":12316,"date":"2019-09-04T12:11:58","date_gmt":"2019-09-04T10:11:58","guid":{"rendered":"https:\/\/help.heredis.com\/?p=12316"},"modified":"2022-01-05T23:09:34","modified_gmt":"2022-01-05T22:09:34","slug":"zeugen-und-teilnehmer-hinzufuegen","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/","title":{"rendered":"Zeugen und Teilnehmer hinzuf\u00fcgen"},"content":{"rendered":"<p>Geben Sie auf der Grundlage der in Ihrem Besitz befindlichen Urkunden oder Dokumente an, wer die Personen sind, die an Ereignissen teilgenommen haben (Zeugen, Anwesende, Standesbeamte etc.).<\/p>\n<p><strong>Zeugen und Teilnehmer<\/strong> werden in der Ansicht <strong>Daten &gt; Personenbezogene Daten<\/strong> angezeigt. Sie k\u00f6nnen f\u00fcr jedes gew\u00e4hlte Ereignis auf sie zugreifen, indem Sie auf die Registerkarte <strong>Zeugen<\/strong> oder <strong>Teilnehmer<\/strong> klicken. Ist mindestens eine Person mit dem Ereignis verbunden, wird auf dieser Registerkarte sowie im Themenbereich <strong>Beziehungen<\/strong> der Werkzeugleiste ein blauer Balken angezeigt.<\/p>\n<h3>Eine neue Person hinzuf\u00fcgen<\/h3>\n<p><em>Zeuge oder Teilnehmer hinzuf\u00fcgen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-14483\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg\" alt=\"\" width=\"545\" height=\"256\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg 500w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1-300x141.jpg 300w\" sizes=\"(max-width: 545px) 100vw, 545px\" \/><\/p>\n<p>1. Klicken Sie auf die Registerkarte <strong>Zeugen<\/strong> oder <strong>Teilnehmer<\/strong> in dem Informationsbereich der Ereignisse. Die Registerkarte <strong>Zeugen<\/strong> wird zu <strong>Teilnehmer<\/strong>, wenn das Ereignis geteilt ist.<br \/>\n2. Klicken Sie in der Aktionsleiste auf <img decoding=\"async\" class=\"alignnone size-full wp-image-1140\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> (Zeuge\/Teilnehmer hinzuf\u00fcgen).<br \/>\n3. Das Fenster <b>Zeuge\/Teilnehmer hinzuf\u00fcgen<\/b>\u00a0\u00f6ffnet sich. Geben Sie die bekannten Informationen \u00fcber diese Person ein.<br \/>\n4. Klicken Sie auf<strong> Erstellen<\/strong>. Die Person wird in die Liste der vorhandenen Personen in Ihrer Datei aufgenommen.<\/p>\n<h3>Eine vorhandene Person verbinden<\/h3>\n<h4>W\u00e4hrend der Dateneingabe f\u00fcr ein Ereignis<\/h4>\n<p>1. Klicken Sie auf die Registerkarte <strong>Zeugen<\/strong> oder <strong>Teilnehmer<\/strong> in dem Informationsbereich eines Ereignisses.<br \/>\n2. Klicken Sie in der Aktionsleiste auf <img decoding=\"async\" class=\"alignnone size-full wp-image-1140\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> (Zeuge\/Teilnehmer hinzuf\u00fcgen).<br \/>\n3. Das Fenster <strong>Person erstellen oder ausw\u00e4hlen<\/strong>\u00a0\u00f6ffnet sich. Geben Sie den Nachnamen oder Vornamen im Abschnitt <strong>Personenbezogene Angaben <\/strong>ein und w\u00e4hlen Sie die zu verbindende Person in der Liste<strong> Vorhandene Personen <\/strong>rechts im Fenster aus. Klicken Sie<strong> Ausw\u00e4hlen <\/strong>oder doppelklicken Sie auf den Namen in der Liste.<br \/>\n4. F\u00fcllen Sie die Informationsfelder zu der Verbindung aus und best\u00e4tigen Sie mit <strong>OK<\/strong>.<\/p>\n<h4>Drag &amp; Drop<\/h4>\n<p>1. W\u00e4hlen Sie das betroffene Ereignis auf der Ansicht <strong>Personenbezogene Daten<\/strong>.<br \/>\n2. Ziehen Sie die zu verbindende Person von einer der Seitenleisten (Themenbereich <strong>Personen<\/strong>, <strong>Favoriten<\/strong>, <strong>Beziehungen<\/strong> \u2026) auf den Informationsbereich des Ereignisses.<br \/>\n3. F\u00fcllen Sie die Informationsfelder zu der Verbindung aus und best\u00e4tigen Sie mit <strong>OK<\/strong>.<\/p>\n<h3>Eine neue Person mit ihren Zeugen hinzuf\u00fcgen<\/h3>\n<p>Um w\u00e4hrend der Dateneingabe f\u00fcr eine neue Person Zeugen zu einem Ereignis hinzuzuf\u00fcgen, nutzen Sie den Anzeigemodus <strong>Komplett<\/strong> oder <strong>Personalisiert<\/strong>, indem Sie auf das Zahnrad <img decoding=\"async\" class=\"alignnone size-full wp-image-17424\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/05\/roue-dentee.png\" alt=\"\" width=\"16\" height=\"16\" \/>\u00a0im Fenster <strong>Person erstellen oder ausw\u00e4hlen <\/strong>klicken. Siehe auch den Artikel <a href=\"https:\/\/help.heredis.com\/de\/heredis-personalisieren\/\">Heredis personalisieren &gt; Anzeigemodus der Dateneingabe ausw\u00e4hlen.<\/a><\/p>\n<p>1. Klappen Sie das Eingabefeld <strong>Zeugen<\/strong> auf (klicken Sie auf den Aufklapp-Pfeil, wenn das Feld zugeklappt ist).<br \/>\n2. Klicken Sie auf der Aktionsleiste unter dem Feld <strong>Zeugen<\/strong> auf den Button +.<br \/>\n3. Das Fenster <strong>Person erstellen oder ausw\u00e4hlen <\/strong>f\u00fcr den Zeugen \u00f6ffnet sich. Geben Sie die bekannten Informationen \u00fcber den Zeugen ein und klicken Sie auf <strong>Erstellen<\/strong> oder w\u00e4hlen Sie eine vorhandene Person und klicken Sie auf <strong>Ausw\u00e4hlen<\/strong>.<br \/>\n4. Geben Sie Informationen \u00fcber die Verbindung mit dem Zeugen ein und best\u00e4tigen Sie mit <strong>OK<\/strong>. Der Zeuge wird dem Feld <strong>Zeugen<\/strong> des Eingabefensters hinzugef\u00fcgt.<br \/>\n5. Geben Sie einen weiteren Zeugen oder weitere Daten f\u00fcr die prim\u00e4re Person ein.<\/p>\n<p><em>(Windows) Zeuge bei der Eingabe einer neuen Person hinzuf\u00fcgen<\/em><\/p>\n<p><em><img decoding=\"async\" class=\"alignnone wp-image-47130\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_pc_DE.png\" alt=\"\" width=\"688\" height=\"550\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_pc_DE.png 1183w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_pc_DE-300x240.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_pc_DE-1024x819.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_pc_DE-768x614.png 768w\" sizes=\"(max-width: 688px) 100vw, 688px\" \/><\/em><\/p>\n<p><em>(Mac) Zeuge bei der Eingabe einer neuen Person hinzuf\u00fcgen<\/em><\/p>\n<h3><img decoding=\"async\" class=\"alignnone wp-image-47127\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1.png\" alt=\"\" width=\"683\" height=\"489\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1.png 1610w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1-300x215.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1-1024x733.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1-768x550.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_ajout_indi_mac_DE-1-1536x1099.png 1536w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/h3>\n<h3>Eine Verbindung mit einem Zeugen oder Teilnehmer \u00e4ndern<\/h3>\n<p>Jede Person in der Genealogie-Datei kann einem oder mehreren Ereignissen zugewiesen werden. Geben Sie die bekannten Informationen \u00fcber ihre Rolle bei dem Ereignis ein.<\/p>\n<p>\u00c4ndern oder vervollst\u00e4ndigen Sie diese Information in der Ansicht <strong>Daten &gt; Personenbezogene Daten<\/strong>.<br \/>\n1. W\u00e4hlen Sie das Ereignis und klicken Sie auf die Registerkarte<strong> Zeugen<\/strong> oder <strong>Teilnehmer <\/strong>im Informationsbereich des Ereignisses.<br \/>\n2. W\u00e4hlen Sie die zu \u00e4ndernde Verbindung mit einem Zeugen\/Teilnehmer und klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-1130\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-edit.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> <strong>Gew\u00e4hlten Zeugen\/Teilnehmer bearbeiten<\/strong> oder doppelklicken Sie auf die Zeile.<br \/>\n3. Bearbeiten Sie die Informationen \u00fcber die Verbindung.<\/p>\n<h4>Rolle<\/h4>\n<p>Geben Sie die Rolle der Person in dem gew\u00e4hlten Ereignis an: Die Person kann ein Teilnehmer an einem Ereignis (Zeuge, religi\u00f6ser Amtstr\u00e4ger, Pate, etc.) sein oder als Nichtteilnehmer erw\u00e4hnt sein (verstorbener Verwandter, Notar, der einen Vertrag registriert hat, etc.).<br \/>\nW\u00e4hlen Sie die entsprechende Rolle in der Dropdown-Liste aus.<\/p>\n<p><em>(Windows) Rolle des Zeugen<\/em><\/p>\n<p><em><img decoding=\"async\" class=\"alignnone wp-image-47136\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_PC_DE.png\" alt=\"\" width=\"538\" height=\"259\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_PC_DE.png 847w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_PC_DE-300x145.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_PC_DE-768x370.png 768w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/><\/em><\/p>\n<p><em>(Mac) Rolle des Zeugen<\/em><\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-47133\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE.png\" alt=\"\" width=\"738\" height=\"147\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE.png 1820w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE-300x60.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE-1024x204.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE-768x153.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/temoins_role_mac_DE-1536x306.png 1536w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/h4>\n<h4>Alter<\/h4>\n<p>\u2022 Alter\/Dokument: Viele Urkunden geben das Alter des Zeugen am Tag des Ereignisses an. F\u00fcllen Sie das Feld <strong>Alter\/Dokument<\/strong> aus.<br \/>\n\u2022 Tats\u00e4chliches Alter: Um Ihnen bei der Pr\u00fcfung der Wahl einer vorhandenen Person als Zeuge zu helfen, errechnet und zeigt Heredis das Alter am Tag des Ereignisses an. Wenn es sich sehr vom Alter auf der Urkunde unterscheidet, haben Sie vermutlich ein Homonym gew\u00e4hlt. L\u00f6schen Sie die Verbindung und w\u00e4hlen Sie eine andere Person oder pr\u00fcfen Sie die Daten, die vielleicht falsch sind.<br \/>\nWenn f\u00fcr den Zeugen oder Teilnehmer kein bekanntes Geburtsdatum vorliegt, kann Heredis mit dem Alter auf der Urkunde automatisch das Geburtsdatum errechnen.<\/p>\n<h4>Kommentare<\/h4>\n<p>Geben Sie einen Kommentar zur Verbindung zwischen der Person und dem Ereignis ein. In den meisten F\u00e4llen werden hier Angaben zu Beruf, Wohnort und Beziehungen verwendet, wie sie auf den Urkunden vermerkt sind.<br \/>\nNachdem Sie die Eingabe oder die \u00c4nderung des Zeugen oder Teilnehmers best\u00e4tigt haben, erscheint der Kommentar in der Liste der Zeugen oder Teilnehmer.<\/p>\n<h3>Verbindung zwischen einem Zeugen oder Teilnehmer und einem Ereignis aufheben<\/h3>\n<p>1. W\u00e4hlen Sie in der Ansicht <strong>Daten &gt; Personenbezogene Daten<\/strong> das Ereignis und klicken Sie auf die Registerkarte<strong> Zeugen<\/strong> oder <strong>Teilnehmer<\/strong>.<br \/>\n2. Klicken Sie in der Aktionsleiste unter dem Ereignis auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-1141\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-moins.jpg\" alt=\"\" width=\"16\" height=\"16\" \/> (Gew\u00e4hlten Zeugen\/Teilnehmer entfernen).<br \/>\n3. Best\u00e4tigen Sie mit <strong>OK.<\/strong><\/p>\n<p>Die Person wird von dem Ereignis entfernt. Sie steht aber in Ihrer Genealogie-Datei weiterhin zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geben Sie auf der Grundlage der in Ihrem Besitz befindlichen Urkunden oder Dokumente an, wer die Personen sind, die an [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[144],"class_list":["post-12316","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden","tag-dateneingabe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Geben Sie auf der Grundlage der in Ihrem Besitz befindlichen Urkunden oder Dokumente an, wer die Personen sind, die an [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-04T10:11:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-05T22:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Zeugen und Teilnehmer hinzuf\u00fcgen\",\"datePublished\":\"2019-09-04T10:11:58+00:00\",\"dateModified\":\"2022-01-05T22:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/\"},\"wordCount\":901,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Add-a-witness_DE-1.jpg\",\"keywords\":[\"Dateneingabe\"],\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/\",\"name\":\"Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Add-a-witness_DE-1.jpg\",\"datePublished\":\"2019-09-04T10:11:58+00:00\",\"dateModified\":\"2022-01-05T22:09:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Add-a-witness_DE-1.jpg\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Add-a-witness_DE-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/zeugen-und-teilnehmer-hinzufuegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeugen und Teilnehmer hinzuf\u00fcgen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/","og_locale":"de_DE","og_type":"article","og_title":"Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase","og_description":"Geben Sie auf der Grundlage der in Ihrem Besitz befindlichen Urkunden oder Dokumente an, wer die Personen sind, die an [...]","og_url":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2019-09-04T10:11:58+00:00","article_modified_time":"2022-01-05T22:09:34+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg","type":"","width":"","height":""}],"author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Zeugen und Teilnehmer hinzuf\u00fcgen","datePublished":"2019-09-04T10:11:58+00:00","dateModified":"2022-01-05T22:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/"},"wordCount":901,"image":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg","keywords":["Dateneingabe"],"articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/","url":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/","name":"Zeugen und Teilnehmer hinzuf\u00fcgen - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg","datePublished":"2019-09-04T10:11:58+00:00","dateModified":"2022-01-05T22:09:34+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Add-a-witness_DE-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/zeugen-und-teilnehmer-hinzufuegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Zeugen und Teilnehmer hinzuf\u00fcgen"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=12316"}],"version-history":[{"count":14,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12316\/revisions"}],"predecessor-version":[{"id":47139,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12316\/revisions\/47139"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=12316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=12316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=12316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}