{"id":12314,"date":"2024-09-03T15:35:32","date_gmt":"2024-09-03T13:35:32","guid":{"rendered":"https:\/\/help.heredis.com\/?p=12314"},"modified":"2025-11-13T10:52:07","modified_gmt":"2025-11-13T09:52:07","slug":"weitere-namen","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/weitere-namen\/","title":{"rendered":"Weitere Namen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8220;&#8220;]Es kam fr\u00fcher oft vor, dass eine Person mehrere Vornamen und Nachnamen trug. So kam es oft vor, dass der Vorname oder Geburtsname vom dem abweicht, der im allt\u00e4glichen Leben verwendet wurde. Hier sind einige Beispiele f\u00fcr die Gr\u00fcnde daf\u00fcr:<\/p>\n<ul>\n<li>Erw\u00fcnschte Namens\u00e4nderung bei der Einwanderung<\/li>\n<li>Anpassung des Namens bei der Einwanderung an das neue Land<\/li>\n<li>Rechtschreib\u00e4nderungen der Nachnamen, da sich unsere Vorfahren h\u00e4ufig auf die m\u00fcndliche \u00dcberlieferung verlie\u00dfen oder wenn der Pfarrer nicht aus der Region stammte.<\/li>\n<li>Erw\u00fcnschte Namens\u00e4nderung bei einer Adoption oder einer Geschlechtsumwandung.<\/li>\n<li>usw.<\/li>\n<\/ul>\n<p>Um alles \u00fcber die Eingabe eines Nachnamens zu erfahren, lesen Sie den Artikel <a href=\"https:\/\/help.heredis.com\/de\/einfache-nachnamen-zusammengesetzte-nachnamen-oder-mehrere-nachnamen-eingeben\/\">Einfache Nachnamen, zusammengesetzte Nachnamen oder mehrere Nachnamen eingeben<\/a>.<\/p>\n<h3>Weitere Vor- und Nachnamen eingeben<\/h3>\n<p>W\u00e4hlen Sie die gew\u00fcnschte Person als prim\u00e4re Person.<br \/>\nGehen Sie auf die Registerkarte <strong>Weitere Namen<\/strong> in der Ansicht <strong>Personenbezogene Daten<\/strong> der Hauptregisterkarte <strong>Daten<\/strong>.<br \/>\nUm einen weiteren Namen hinzuzuf\u00fcgen, klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone wp-image-1140\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>.<br \/>\nGeben Sie alle Informationen ein, die Sie dazu haben, wie Nachnamen, Pr\u00e4fix, Suffix, Vornamen, Spitzname, und w\u00e4hlen Sie den entsprechenden Namentyp aus der Dropdown-Liste aus.<br \/>\nWenn der von Ihnen eingegebene weitere Name keinen der vorhanden Typen zugeordnet werden kann, w\u00e4hlen Sie <strong>Sonstige<\/strong> und erstellen Sie Ihren eigenen Datentyp. Sie haben ebenfalls die M\u00f6glichkeit die von Heredis definierten Typen umzubenennen.<br \/>\n<strong>(Windows)\u00a0<\/strong>Ersetzen Sie <strong>Sonstige<\/strong> mit dem gew\u00fcnschten Datentyp.<br \/>\n<strong>(Mac)<\/strong> Geben Sie den gew\u00fcnschten Datentyp entsprechend in das leere Feld ein.<\/p>\n<p style=\"text-align: left;\"><em>Windows: Weitere Namen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-14971\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate-names_DE.jpg\" alt=\"\" width=\"952\" height=\"203\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate-names_DE.jpg 769w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate-names_DE-300x64.jpg 300w\" sizes=\"(max-width: 952px) 100vw, 952px\" \/><\/p>\n<p style=\"text-align: left;\"><em>Mac: Weitere Namen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-19827\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE.png\" alt=\"\" width=\"1774\" height=\"296\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE.png 1774w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE-300x50.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE-1024x171.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE-768x128.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Alternate_names_Mac_DE-1536x256.png 1536w\" sizes=\"(max-width: 1774px) 100vw, 1774px\" \/><\/p>\n<p>Die Registerkarte <strong>Weitere Namen <\/strong>ist mit einem blauen Punkt markiert, wenn ein weiterer Name vorhanden ist.<\/p>\n<h3>Namen mit unterschiedlichen Schreibweisen<\/h3>\n<p>In der Registerkarte <strong>Weitere Namen<\/strong> haben Sie die M\u00f6glichkeit, die unterschiedlichen Schreibweisen eines Nachnamens einzugeben und in welchem Dokument Sie diese gefunden haben. Zum Beispiel \u00e4nderte sich der Name Schmit bei der Heirat zu Schmidt im Sterbeeintrag. Es erm\u00f6glicht Ihnen, die unterschiedlichen Schreibweisen des Namens einer Person zu erkennen.<\/p>\n<p>Varianten f\u00fcr Nachnamen erstellen<\/p>\n<ul>\n<li>\u00d6ffnen Sie den Nachnamen-Index.<\/li>\n<li>W\u00e4hlen Sie die Hauptform f\u00fcr den Nachnamen.<\/li>\n<li>Klicken Sie im Feld\u00a0<strong>Varianten<\/strong> auf <img decoding=\"async\" class=\"alignnone size-full wp-image-11936\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/16-plus.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>.<\/li>\n<li>W\u00e4hlen Sie die andere Schreibweise des Nachnamens als Variante aus.<\/li>\n<\/ul>\n<p><em>Windows: Variante eines Nachnamens<\/em><\/p>\n<p><em><img decoding=\"async\" class=\"alignnone wp-image-54093\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_PC_DE.png\" alt=\"\" width=\"651\" height=\"569\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_PC_DE.png 866w, https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_PC_DE-300x262.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_PC_DE-768x671.png 768w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/em><\/p>\n<p><em>Mac: Variante eines Nachnamens<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-53916\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE.png\" alt=\"\" width=\"653\" height=\"404\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE.png 1868w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE-300x186.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE-1024x634.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE-768x475.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Mac_DE-1536x951.png 1536w\" sizes=\"(max-width: 653px) 100vw, 653px\" \/><\/p>\n<p>Durch das Eintragen von Varianten kann Heredis die unterschiedlichen Schreibweisen eines Nachnamens in die Liste der vorhandenen Personen einbeziehen, wenn Sie eine neue Person hinzuf\u00fcgen. So vermeiden Sie doppelte Eintr\u00e4ge.<\/p>\n<p><em>Windows: Eine Person hinzuf\u00fcgen<\/em><\/p>\n<p><em><img decoding=\"async\" class=\"alignnone wp-image-54096\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_ajout_PC_DE.png\" alt=\"\" width=\"673\" height=\"537\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_ajout_PC_DE.png 984w, https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_ajout_PC_DE-300x240.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2024\/09\/Autres_noms_variantes_ajout_PC_DE-768x613.png 768w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/><\/em><\/p>\n<p><em>Mac: Eine Person hinzuf\u00fcgen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-53919\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE.png\" alt=\"\" width=\"671\" height=\"435\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE.png 2144w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE-300x194.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE-1024x663.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE-768x497.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE-1536x994.png 1536w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Autres_noms_Variantes_Ajout_Indi_Mac_DE-1920x1243.png 1920w\" sizes=\"(max-width: 671px) 100vw, 671px\" \/><\/p>\n<h3>Weitere Namen l\u00f6schen<\/h3>\n<p>Um einen weiteren Namen zu l\u00f6schen, w\u00e4hlen Sie ihn aus der Liste aus. Klicken Sie anschlie\u00dfend auf den Button <img decoding=\"async\" class=\"alignnone wp-image-1141\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-moins.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>.<\/p>\n<p><strong>Hinweis:<\/strong> Im Vornamen- und Nachnamen-Index k\u00f6nnen Elemente gel\u00f6scht werden, wenn sie nicht mehr von einer Person in Ihrer Genealogie verwendet werden.<\/p>\n<p>Die weiteren Namen, die mit einer Person in Ihrer Genealogie-Datei verkn\u00fcpft sind, werden beim Import, beim GEDCOM-Export als auch bei der Fusion automatisch von Heredis verwaltet.<\/p>\n<h3>Verwendung der weiteren Namen<\/h3>\n<p>Wenn Sie eine Person hinzuf\u00fcgen, \u00fcberpr\u00fcft Heredis auch die weiteren Namen und zeigt sie in der Liste der bereits vorhandenen Personen an. So vermeiden Sie doppelte Eintr\u00e4ge.<\/p>\n<p>Seit Heredis 2025 k\u00f6nnen Sie die weiteren Namen in den B\u00fcchern und Stammkarten anzeigen lassen, wenn Sie die entsprechende Option aktivieren.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Es kam fr\u00fcher oft vor, dass eine Person mehrere Vornamen und Nachnamen trug. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[144],"class_list":["post-12314","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden","tag-dateneingabe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weitere Namen - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/weitere-namen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weitere Namen - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Es kam fr\u00fcher oft vor, dass eine Person mehrere Vornamen und Nachnamen trug. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/weitere-namen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T13:35:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T09:52:07+00:00\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Weitere Namen\",\"datePublished\":\"2024-09-03T13:35:32+00:00\",\"dateModified\":\"2025-11-13T09:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/\"},\"wordCount\":558,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/16-plus.jpg\",\"keywords\":[\"Dateneingabe\"],\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/\",\"name\":\"Weitere Namen - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/16-plus.jpg\",\"datePublished\":\"2024-09-03T13:35:32+00:00\",\"dateModified\":\"2025-11-13T09:52:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/16-plus.jpg\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/16-plus.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/weitere-namen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weitere Namen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weitere Namen - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/weitere-namen\/","og_locale":"de_DE","og_type":"article","og_title":"Weitere Namen - Heredis Help Knowledgebase","og_description":"Es kam fr\u00fcher oft vor, dass eine Person mehrere Vornamen und Nachnamen trug. [...]","og_url":"https:\/\/help.heredis.com\/de\/weitere-namen\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2024-09-03T13:35:32+00:00","article_modified_time":"2025-11-13T09:52:07+00:00","author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Weitere Namen","datePublished":"2024-09-03T13:35:32+00:00","dateModified":"2025-11-13T09:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/"},"wordCount":558,"image":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg","keywords":["Dateneingabe"],"articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/","url":"https:\/\/help.heredis.com\/de\/weitere-namen\/","name":"Weitere Namen - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg","datePublished":"2024-09-03T13:35:32+00:00","dateModified":"2025-11-13T09:52:07+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/weitere-namen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/16-plus.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/weitere-namen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Weitere Namen"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=12314"}],"version-history":[{"count":20,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12314\/revisions"}],"predecessor-version":[{"id":55849,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12314\/revisions\/55849"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=12314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=12314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=12314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}