{"id":12288,"date":"2019-10-28T11:49:13","date_gmt":"2019-10-28T10:49:13","guid":{"rendered":"https:\/\/help.heredis.com\/?p=12288"},"modified":"2021-11-30T12:14:45","modified_gmt":"2021-11-30T11:14:45","slug":"datumsangaben","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/datumsangaben\/","title":{"rendered":"Datumsangaben"},"content":{"rendered":"<h3>Anerkannte Kalender<\/h3>\n<p>Heredis bearbeitet die eingegebenen Daten in 4 verschiedenen Kalendern: dem gregorianischen, julianischen, j\u00fcdischen Kalender und dem franz\u00f6sischen Revolutionskalender. Die Daten m\u00fcssen zwischen 4712 v. Chr. und 3454 nach Chr. des gregorianischen Kalenders liegen.<\/p>\n<p>Der heute in den meisten L\u00e4ndern der Welt verwendete gregorianische Kalender wurde 1582 eingef\u00fchrt und in den verschiedenen L\u00e4ndern zu sehr unterschiedlichen Zeitpunkten angewandt (vom 14. bis 20. Jahrhundert). Daten, die vor der Einf\u00fchrung des gregorianischen Kalenders liegen, gelten als im julianischen Kalender ausgedr\u00fcckt.<\/p>\n<p>Der julianische Kalender wurde vom gregorianischen Kalender abgel\u00f6st. In manchen L\u00e4ndern wurde er bis zum 20. Jahrhundert verwendet.<\/p>\n<p>Der j\u00fcdische Kalender wird in Dokumenten von Familien j\u00fcdischen Glaubens angewandt, unabh\u00e4ngig von dem Land, in dem sie leben.<\/p>\n<p>Der franz\u00f6sische Revolutionskalender wurde nur in Frankreich angewandt und deckt den Zeitraum vom 22. September 1792 bis zum 1. Januar 1806 ab.<\/p>\n<hr \/>\n<h3>Dateneingabe<\/h3>\n<p>Heredis konvertiert Daten, die sowohl in Zahlen (mit Hilfe der Trennzeichen . oder \/ oder Leerzeichen) als auch mit dem Monat als Text (vollst\u00e4ndig oder abgek\u00fcrzt) eingegeben werden.<\/p>\n<p>Sie k\u00f6nnen ein Datum in den gregorianischen, julianischen, j\u00fcdischen Kalender oder in den franz\u00f6sischen Revolutionskalender eingeben. Gibt es keinen Monatsnamen, der f\u00fcr den j\u00fcdischen Kalender oder den franz\u00f6sischen Revolutionskalender charakteristisch ist, geht Heredis davon aus, dass das Datum im gregorianischen Kalender ausgedr\u00fcckt wurde.<\/p>\n<p>Wenn Sie im j\u00fcdischen Kalender ein unvollst\u00e4ndiges Datum eingeben, stellen Sie der Zahl den Buchstaben H (H 1987) voraus.<\/p>\n<p>Um im julianischen Kalender ein Datum nach dem 10. Dezember 1582 einzugeben, stellen Sie der Zahl den Buchstaben J (J 23. Juni 1654) voraus.<\/p>\n<p>Um ein Datum im franz\u00f6sischen Revolutionskalender einzugeben, geben Sie das Jahr in r\u00f6mischen oder arabischen Zahlen ein und stellen Sie eventuell das Wort \u201eAn\u201c voraus. Geben Sie das Wort \u201ecomp\u201c f\u00fcr die Erg\u00e4nzungstage (<em>frz. jour compl\u00e9mentaire<\/em>) ein (z. B. \u201e6 comp an III\u201c f\u00fcr den sechsten Erg\u00e4nzungstag des Jahres III der Republik).<\/p>\n<h4>Anerkannte Formate<\/h4>\n<p>Damit Heredis das Datum in der von Ihnen gew\u00fcnschten Reihenfolge anzeigt, w\u00e4hlen Sie<strong> (Windows) Werkzeuge &gt; Pr\u00e4ferenzen &gt; Heredis-Pr\u00e4ferenzen &gt; Format<\/strong>; <strong>(Mac) Heredis &gt; Pr\u00e4ferenzen &gt; Format<\/strong> und w\u00e4hlen Sie die Reihenfolge der angezeigten Elemente (Tag\/Monat\/Jahr oder Monat\/Tag\/Jahr).<\/p>\n<p>Wenn Sie die Reihenfolge Tag\/Monat\/Jahr festgelegt haben, kann das Datum \u201e2. Februar 1794\u201c wie folgt eingegeben werden:<\/p>\n<p>Gregorianischer Kalender<br \/>\n\u2022 2. Februar 1794<br \/>\n\u2022 2. Feb 1794<br \/>\n\u2022 02\/02\/1794<br \/>\n\u2022 02.02.1794<\/p>\n<p>Julianischer Kalender<br \/>\n\u2022 J 22. Januar 1794<br \/>\n\u2022 J 2. Jan 1794<br \/>\n\u2022 J 22\/1\/1794<br \/>\n\u2022 J 22.01.1794<\/p>\n<p>J\u00fcdischer Kalender<br \/>\n\u2022 2 AdarI 5554<\/p>\n<p>Franz\u00f6sischer Revolutionskalender<br \/>\n\u2022 14 pluvi\u00f4se an 2<br \/>\n\u2022 14 pluv an II<br \/>\n\u2022 14 pluv 2<br \/>\n\u2022 14 pluvi\u00f4se II<\/p>\n<p><strong>Info<\/strong> \u2022 Aktivieren Sie f\u00fcr jedes gedruckte Dokument und jede exportierte Datei die Option <strong>Gregorianischen Kalender verwenden<\/strong>. Dies garantiert die Kompatibilit\u00e4t mit allen Programmen, da einige Genealogieprogramme die verschiedenen Kalender in ihren GEDCOM-Importen nicht ber\u00fccksichtigen.<\/p>\n<h4>Zeitr\u00e4ume und ungef\u00e4hre Daten<\/h4>\n<p>Heredis verwaltet die Chronologie der Ereignisse nach den eingegebenen (genauen oder ungef\u00e4hren) Daten. Verwenden Sie Schl\u00fcsselw\u00f6rter, um Zeitr\u00e4ume oder ungef\u00e4hre Daten auszudr\u00fccken.<\/p>\n<p><em>Vor<\/em><br \/>\nGeben Sie das Wort <strong>vor<\/strong> oder das Zeichen &lt; gefolgt von einem Leerzeichen oder dem Symbol \/ ohne Leerzeichen und dann das Datum (vollst\u00e4ndig oder unvollst\u00e4ndig) in Zahlen oder den Monat als Text ein.<br \/>\n\u2022 vor 23. August 1845<br \/>\n\u2022 &lt; 23\/8\/1845<br \/>\n\u2022 \/23.08.1845<\/p>\n<p><em>Nach<\/em><br \/>\nGeben Sie das Wort <strong>nach<\/strong> oder das Zeichen &gt; gefolgt von einem Leerzeichen und dann das Datum (vollst\u00e4ndig oder unvollst\u00e4ndig) in Zahlen oder den Monat als Text ein. Oder geben Sie das Zeichen \/ ohne Leerzeichen nach dem Datum ein.<br \/>\n\u2022 nach 6. Juni 1774<br \/>\n\u2022 nach 6\/6\/1774<br \/>\n\u2022 6.6.1774\/<\/p>\n<p><em>Um\/Circa<\/em><br \/>\nGeben Sie die W\u00f6rter <strong>um<\/strong> oder <strong>circa<\/strong> oder die Abk\u00fcrzung <strong>ca<\/strong> oder das Zeichen ~ gefolgt von einem Leerzeichen und dann das Datum (vollst\u00e4ndig oder unvollst\u00e4ndig) in Zahlen oder den Monat als Text ein.<br \/>\n\u2022 um Februar 1811<br \/>\n\u2022 circa 2\/1811<br \/>\n\u2022 ca 2.1811<br \/>\n\u2022 ~2.1811<\/p>\n<p><em>Zwischen &#8230; und <\/em><br \/>\nGeben Sie die W\u00f6rter <strong>zwischen<\/strong> und dann <strong>und<\/strong> oder die Zeichenfolge &lt;&gt; und &amp; gefolgt von dem Datum (vollst\u00e4ndig oder unvollst\u00e4ndig) in Zahlen oder den Monat als Text ein oder tippen Sie die Zeichenfolge \/\/ zwischen die beiden Daten ohne Leerzeichen.<br \/>\n\u2022 zwischen 11. Oktober 1914 und April 1917<br \/>\n\u2022 zwischen 11\/10\/1914 und 4\/1917<br \/>\n\u2022&lt;&gt; 11. Oktober 1914 &amp; 04 1917<br \/>\n\u2022 11.10.1914\/\/4.1917<\/p>\n<p><em>Von \u2026 bis<\/em><br \/>\nGeben Sie das Wort <strong>von<\/strong> ein, gefolgt von einem Leerzeichen und dann das Datum (vollst\u00e4ndig oder unvollst\u00e4ndig) gefolgt von einem Leerzeichen und dem Wort<strong> bis<\/strong> gefolgt von dem vollst\u00e4ndigen Datum.<br \/>\n\u2022 von 1845 bis 1846<br \/>\n\u2022 von 8\/1845 bis 9\/1845<br \/>\n\u2022 von Oktober 1844 bis September 1845<br \/>\n\u2022 von 23\/8\/1845 bis 31\/8\/1845<\/p>\n<p><em>Vor Christus<\/em><br \/>\nGeben Sie die Abk\u00fcrzung <strong>B.C.<\/strong> nach dem Datum ein oder setzen Sie vor dem Datum ein <strong>Minuszeichen<\/strong>, um Zeitr\u00e4ume vor Christus anzugeben.<br \/>\n\u2022 125 B.C.<br \/>\n\u2022 -125<\/p>\n<p>Vor einem vollst\u00e4ndigen oder unvollst\u00e4ndigen Datum k\u00f6nnen Sie folgende Schl\u00fcsselw\u00f6rter hinzuf\u00fcgen:<br \/>\n\u2022 <strong>Gesch\u00e4tzt<\/strong> oder <strong>est<\/strong> (<em>estimated<\/em>), wenn es sich bei dem Datum um eine reine Vermutung handelt. In diesem Fall wird das Datum hinter dem Wort \u201egesch\u00e4tzt\u201c oder <strong>(est)<\/strong> angezeigt. Es wird in chronologischer Reihenfolge ber\u00fccksichtigt (z. B. Reihenfolge der Partnerschaften, Reihenfolge der Kinder &#8230;), erscheint aber nicht in gedruckten Dokumenten.<br \/>\n\u2022\u00a0<strong>Errechnet<\/strong> oder <strong>cal<\/strong> (<em>calculated<\/em>), um anzugeben, dass ein Datum durch Errechnung ermittelt wurde. Wenn Sie zum Beispiel das Geburtsdatum einer Person nicht kennen, aber das Todesjahr auf der Sterbeurkunde gefunden haben, zeigt das Programm automatisch ein errechnetes Geburtsdatum an. Der Nutzer kann auch das Wort errechnet vor einem Datum eingeben, das er abgeleitet hat. Die errechneten Daten werden angezeigt und ausgedruckt, indem die W\u00f6rter \u201eerrechnet\u201c oder <strong>(c)<\/strong> vorangestellt werden.<\/p>\n<p><strong>Info<\/strong> \u2022 Nach den in einem g\u00fcltigen Format eingegebenen Daten k\u00f6nnen Sie einen Kommentar hinzuf\u00fcgen, der Ihre Arbeit eventuell erleichtert, vorausgesetzt, Sie setzen ihn in Klammern. So k\u00f6nnen Sie z. B. 1875 (Anfang Sommer) oder Juni 1674 (unbest\u00e4tigt) angeben.<\/p>\n<h3>Automatische Errechnung von Geburtsdaten<\/h3>\n<p>Heredis berechnet automatisch das Geburtsdatum von Personen, deren Alter zu einem bestimmten Ereignis bekannt ist. Das Alter des Vaters, das auf einer Geburtsurkunde angegeben ist, erm\u00f6glicht Ihnen, den Vater mit dem vermutlichen Geburtsjahr zu erstellen oder zu vervollst\u00e4ndigen. Dies erleichtert Ihnen die Suche nach der Geburtsurkunde des Vaters und bringt Sie in Ihrer Genealogie weiter.<\/p>\n<h4>F\u00fcr die Person, die das Ereignis erlebt hat<\/h4>\n<p>1. Erstellen Sie ein Ereignis und geben Sie das Datum an.<br \/>\n2. F\u00fcgen Sie die Zeugen hinzu (Zeuge, Anzeigender, etc.) und geben Sie deren Alter im Feld <strong>Alter\/Dokument<\/strong> des Eingabefensters f\u00fcr die Verbindung ein.<br \/>\n<strong>Info<\/strong> \u2022 Vergessen Sie nicht, durch Klicken auf das Zahnrad <img decoding=\"async\" class=\"alignnone size-full wp-image-12825\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/roue_dent\u00e9e_2.png\" alt=\"\" width=\"29\" height=\"29\" \/> den Eingabemodus <strong>Personalisiert<\/strong> oder <strong>Komplett<\/strong> zu w\u00e4hlen, um dieses Feld anzuzeigen.<\/p>\n<h4>Zeugen eines Ereignisses<\/h4>\n<p>1. Erstellen Sie ein Ereignis und geben Sie das Datum an.<br \/>\n2. F\u00fcgen Sie die Zeugen hinzu (Zeuge, Anzeigender, etc.), und geben Sie deren Alter im Feld <strong>Alter\/Dokument<\/strong> des Eingabefensters f\u00fcr die Verbindung ein.<br \/>\nWenn das Datum des Lebensbeginns (Geburt oder Taufe) bereits existiert, bleiben Ihre Daten nat\u00fcrlich unver\u00e4ndert. Ist das Datum des Lebensbeginns unbekannt, wird Heredis ein errechnetes Geburtsdatum hinzuf\u00fcgen.<br \/>\n<em><strong>Info<\/strong> <\/em>\u2022 Die errechneten Daten werden in der Liste der Ereignisse im Bildschirm<strong> Personenbezogene Daten<\/strong> kursiv angezeigt. Ein (c) wird dem Datum vorangestellt.<\/p>\n<p>Lesen Sie auch den Artikel \u00fcber den <a href=\"https:\/\/help.heredis.com\/de\/datumsrechner\/\">Datumsrechner<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anerkannte Kalender<br \/>\nHeredis bearbeitet die eingegebenen Daten in 4 verschiedenen Kalendern: dem gregorianischen, julianischen, j\u00fcdischen Kalender und dem franz\u00f6sischen Revolutionskalender. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[142],"class_list":["post-12288","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden","tag-werkzeuge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datumsangaben - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/datumsangaben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datumsangaben - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Anerkannte Kalender Heredis bearbeitet die eingegebenen Daten in 4 verschiedenen Kalendern: dem gregorianischen, julianischen, j\u00fcdischen Kalender und dem franz\u00f6sischen Revolutionskalender. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/datumsangaben\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-28T10:49:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-30T11:14:45+00:00\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Datumsangaben\",\"datePublished\":\"2019-10-28T10:49:13+00:00\",\"dateModified\":\"2021-11-30T11:14:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/\"},\"wordCount\":1148,\"keywords\":[\"Werkzeuge\"],\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/\",\"name\":\"Datumsangaben - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"datePublished\":\"2019-10-28T10:49:13+00:00\",\"dateModified\":\"2021-11-30T11:14:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/datumsangaben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datumsangaben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datumsangaben - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/datumsangaben\/","og_locale":"de_DE","og_type":"article","og_title":"Datumsangaben - Heredis Help Knowledgebase","og_description":"Anerkannte Kalender Heredis bearbeitet die eingegebenen Daten in 4 verschiedenen Kalendern: dem gregorianischen, julianischen, j\u00fcdischen Kalender und dem franz\u00f6sischen Revolutionskalender. [...]","og_url":"https:\/\/help.heredis.com\/de\/datumsangaben\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2019-10-28T10:49:13+00:00","article_modified_time":"2021-11-30T11:14:45+00:00","author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Datumsangaben","datePublished":"2019-10-28T10:49:13+00:00","dateModified":"2021-11-30T11:14:45+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/"},"wordCount":1148,"keywords":["Werkzeuge"],"articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/","url":"https:\/\/help.heredis.com\/de\/datumsangaben\/","name":"Datumsangaben - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"datePublished":"2019-10-28T10:49:13+00:00","dateModified":"2021-11-30T11:14:45+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/datumsangaben\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/datumsangaben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datumsangaben"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=12288"}],"version-history":[{"count":12,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12288\/revisions"}],"predecessor-version":[{"id":47030,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12288\/revisions\/47030"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=12288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=12288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=12288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}