{"id":12276,"date":"2019-11-14T14:24:26","date_gmt":"2019-11-14T13:24:26","guid":{"rendered":"https:\/\/help.heredis.com\/?p=12276"},"modified":"2024-10-11T16:09:06","modified_gmt":"2024-10-11T14:09:06","slug":"diashow","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/diashow\/","title":{"rendered":"Diashow"},"content":{"rendered":"<p>Die Diashow von Heredis pr\u00e4sentiert Ihnen das Leben Ihrer Vorfahren in Bildern. Dieses Werkzeug stellt mit Ihren Fotos ein Familienalbum zusammen, das in verschiedenen Kapiteln das Leben der prim\u00e4ren Person und deren unmittelbaren Familie repr\u00e4sentiert.<\/p>\n<p>In dieser Funktion werden die Medien der prim\u00e4ren Person sowie die ihrer Familie, insbesondere die Medien von ihren:<\/p>\n<ul>\n<li>Partnern<\/li>\n<li>Kindern<\/li>\n<li>Geschwistern<\/li>\n<li>Eltern<\/li>\n<li>Gro\u00dfeltern<\/li>\n<\/ul>\n<p>F\u00fcr alle zeigt Heredis die Medien der Person, der Partnerschaften, der pers\u00f6nlichen Ereignisse, der Partnerschaftsereignisse sowie der geteilten Ereignisse an. Wenn Sie Medien mit Namen, Vornamen, Berufen und Orten verkn\u00fcpft haben, werden diese tu pu angezeigt.<\/p>\n<p>Wenn Medien bereits bei der prim\u00e4ren Person verwenden sind, erscheinen sie nicht erneut in der Diashow.<\/p>\n<h3>Die Diashow starten<\/h3>\n<p>Um die Diashow einer Person zu starten, soll diese als prim\u00e4re Person angezeigt werden:<\/p>\n<ul>\n<li>Klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone wp-image-557\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png\" alt=\"\" width=\"25\" height=\"25\" \/> unter dem Anzeigebereich des Mediums der prim\u00e4ren Person auf dem Bildschirm <strong>Unmittelbare Familie<\/strong> oder auf der Hauptregisterkarte <strong>Daten<\/strong>.<\/li>\n<li>Klicken Sie in der Men\u00fcleiste auf <strong>(Windows)<\/strong> Berichte; <strong>(Mac)<\/strong> Dokumente<\/li>\n<\/ul>\n<p>Freuen Sie sich \u00fcber die Ergebnisse Ihrer Recherche, w\u00e4hrend die Seiten des Fotoalbums vor Ihren Augen umbl\u00e4ttern.<\/p>\n<ul>\n<li>Mit dem Button<strong> Pause <\/strong><img decoding=\"async\" class=\"alignnone wp-image-558\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/diaporama_pause.png\" alt=\"\" width=\"25\" height=\"25\" \/> rechts oben im Bildschirm k\u00f6nnen Sie auf einer Seite anhalten und zum Beispiel die Kommentare zum Foto lesen.<\/li>\n<li>Klicken Sie auf <strong>Kapitel<\/strong>, um alle Kapitel Ihres Albums anzuzeigen. W\u00e4hlen Sie ein bestimmtes Kapitel und gelangen Sie direkt zu ihm.<\/li>\n<\/ul>\n<p style=\"text-align: left;\"><em>Diashow<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-13049\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE.png\" alt=\"\" width=\"1047\" height=\"589\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE.png 1919w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE-300x169.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE-768x432.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE-1024x576.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE-1170x658.png 1170w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Slideshow_DE-800x450.png 800w\" sizes=\"(max-width: 1047px) 100vw, 1047px\" \/><\/p>\n<h3>Die Diashow einstellen<\/h3>\n<p>Standardm\u00e4\u00dfig pr\u00e4sentiert sich die Diashow im Thema <strong>\u201eAntik\u201c<\/strong>, aber das k\u00f6nnen Sie nach Ihrem Geschmack anpassen. W\u00e4hlen Sie im Men\u00fc <strong>Themen<\/strong> einen anderen Stil. Jedem Thema ist eine eigene Musik zugeordnet, die nicht ge\u00e4ndert werden kann.<\/p>\n<p>Mit dem Audio-Player unten im Bildschirm k\u00f6nnen Sie die Diashow mit Musik untermalen. W\u00e4hrend Sie die Diashow mit Ihrer Familie betrachten, werden die Fotos von Musik begleitet. Den Ton k\u00f6nnen Sie mit dem Button<strong> Ton<\/strong>\u00a0<img decoding=\"async\" class=\"alignnone wp-image-561\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/diaporama_son.png\" alt=\"\" width=\"25\" height=\"25\" \/> ausschalten.<\/p>\n<h3>Bilder der Diashow ausw\u00e4hlen<\/h3>\n<p>Das Programm ist so eingestellt, dass alle Bilder der prim\u00e4ren Person sowie deren unmittelbaren Familie angezeigt werden.<\/p>\n<p>Klicken Sie auf das Zahnrad <img decoding=\"async\" class=\"alignnone wp-image-1121\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/flipbook_roue.png\" alt=\"\" width=\"25\" height=\"25\" \/>und w\u00e4hlen Sie die Bilder f\u00fcr die prim\u00e4re Person, deren Kinder, Partner und Partnerschaften sowie die anderen Personen (Geschwister \u2026) aus.<\/p>\n<p><strong>Hinweis<\/strong>: Andere Bilder beinhalten Bilder zu Orten, Nachnamen, Vornamen, Berufen, Quellen und sind mit der prim\u00e4ren Person verbunden.<\/p>\n<p>Sie k\u00f6nnen durch Aktivieren der entsprechenden Option alle privaten Bilder von Ihrer Diashow ausschlie\u00dfen.<\/p>\n<p><em>Bilder ausw\u00e4hlen<br \/>\n<\/em><\/p>\n<h3><img decoding=\"async\" class=\"alignnone wp-image-54451\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/parametrage_diaporama_de.png\" alt=\"\" width=\"345\" height=\"360\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/parametrage_diaporama_de.png 452w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/parametrage_diaporama_de-287x300.png 287w\" sizes=\"(max-width: 345px) 100vw, 345px\" \/><\/h3>\n<h3>Die Diashow exportieren<\/h3>\n<p>Mit dem Button<strong> Exportieren<\/strong>\u00a0<img decoding=\"async\" class=\"alignnone wp-image-1124\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/flipbook_export.png\" alt=\"\" width=\"25\" height=\"25\" \/> k\u00f6nnen Sie Ihre Diashow mit anderen teilen. Heredis erstellt am Speicherplatz Ihrer Wahl einen Ordner mit dem Fotoalbum der prim\u00e4ren Person, so wie Sie es zusammengestellt haben. Teilen Sie diesen Ordner mit Ihren Verwandten. Diese k\u00f6nnen die Diashow einfach abspielen, indem sie auf den Link<strong> Das Fotoalbum von [\u2026].html<\/strong> klicken, auch wenn sie Heredis nicht installiert haben.<\/p>\n<p>Sie k\u00f6nnen den Ordner auch auf einen USB-Stick oder eine externe Festplatte kopieren und diesen an Ihren Fernseher, Computer oder ein anderes Ger\u00e4t mit USB-Stecker anschlie\u00dfen, um sich die Diashow im Kreise Ihrer Familie anzuschauen.<\/p>\n<p><strong>Hinweis: <\/strong>Es ist notwendig, eine Kopie des gesamten Ordners zu erstellen. Andernfalls wird die Diashow nicht funktionieren.<\/p>\n<p><em>(Windows) Diashow-Ordner<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-54454\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_de.png\" alt=\"\" width=\"683\" height=\"322\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_de.png 793w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_de-300x141.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_de-768x362.png 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/p>\n<p><em>(Mac) Diashow-Ordner<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-54457\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_mac_de.png\" alt=\"\" width=\"682\" height=\"324\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_mac_de.png 917w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_mac_de-300x143.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/11\/diaporama_explorateur_mac_de-768x365.png 768w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/><\/p>\n<p>Mit dem Button <strong>Diashow beenden<\/strong>\u00a0<img decoding=\"async\" class=\"alignnone wp-image-560\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/diaporama_quitter.png\" alt=\"\" width=\"25\" height=\"25\" \/> in der rechten oberen Ecke k\u00f6nnen Sie die Diashow verlassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Diashow von Heredis pr\u00e4sentiert Ihnen das Leben Ihrer Vorfahren in Bildern. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[142],"class_list":["post-12276","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden","tag-werkzeuge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diashow - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/diashow\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diashow - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Die Diashow von Heredis pr\u00e4sentiert Ihnen das Leben Ihrer Vorfahren in Bildern. [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/diashow\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-14T13:24:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-11T14:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Diashow\",\"datePublished\":\"2019-11-14T13:24:26+00:00\",\"dateModified\":\"2024-10-11T14:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/\"},\"wordCount\":552,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/btn_diapo_small.png\",\"keywords\":[\"Werkzeuge\"],\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/\",\"name\":\"Diashow - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/btn_diapo_small.png\",\"datePublished\":\"2019-11-14T13:24:26+00:00\",\"dateModified\":\"2024-10-11T14:09:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/btn_diapo_small.png\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/btn_diapo_small.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/diashow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diashow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diashow - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/diashow\/","og_locale":"de_DE","og_type":"article","og_title":"Diashow - Heredis Help Knowledgebase","og_description":"Die Diashow von Heredis pr\u00e4sentiert Ihnen das Leben Ihrer Vorfahren in Bildern. [...]","og_url":"https:\/\/help.heredis.com\/de\/diashow\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2019-11-14T13:24:26+00:00","article_modified_time":"2024-10-11T14:09:06+00:00","og_image":[{"url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png","type":"","width":"","height":""}],"author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/diashow\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Diashow","datePublished":"2019-11-14T13:24:26+00:00","dateModified":"2024-10-11T14:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/"},"wordCount":552,"image":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png","keywords":["Werkzeuge"],"articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/diashow\/","url":"https:\/\/help.heredis.com\/de\/diashow\/","name":"Diashow - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png","datePublished":"2019-11-14T13:24:26+00:00","dateModified":"2024-10-11T14:09:06+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/diashow\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/diashow\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/diashow\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/btn_diapo_small.png"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/diashow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Diashow"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=12276"}],"version-history":[{"count":11,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12276\/revisions"}],"predecessor-version":[{"id":54460,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12276\/revisions\/54460"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=12276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=12276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=12276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}