{"id":12188,"date":"2020-01-07T10:11:50","date_gmt":"2020-01-07T09:11:50","guid":{"rendered":"https:\/\/help.heredis.com\/?p=12188"},"modified":"2025-09-01T10:18:54","modified_gmt":"2025-09-01T08:18:54","slug":"benutzerdefinierte-listen","status":"publish","type":"post","link":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/","title":{"rendered":"Benutzerdefinierte Listen"},"content":{"rendered":"<p>Diese Funktion bietet Ihnen verschiedene Vorlagen, die Sie je nach Bedarf komplett personalisieren k\u00f6nnen.<\/p>\n<p>Klicken Sie auf das Men\u00fc <strong>(Windows) Berichte &gt; Benutzerdefinierte Listen; (Mac) Dokumente &gt; Benutzerdefinierte Listen<\/strong> und w\u00e4hlen Sie unter den Standardvorlagen des Programms Ihre Liste aus: Vorfahren, Nachfahren, Personen, Ereignisse, Orte, Quellen. Sie k\u00f6nnen auch den Button <img decoding=\"async\" class=\"alignnone wp-image-3720\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/listes-params.png\" alt=\"\" width=\"25\" height=\"25\" \/> in der Symbolleiste benutzen.<\/p>\n<p>Die gew\u00e4hlte Liste wird in einem neuen Heredis-Fenster eingeblendet. So k\u00f6nnen Sie die Daten in Ihrer Datei ansehen und gleichzeitig an Ihrer Genealogie arbeiten.<\/p>\n<p><strong>Hinweis:<\/strong> Wenn Sie w\u00fcnschen, k\u00f6nnen Sie mehrere benutzerdefinierte Listen gleichzeitig \u00f6ffnen.<\/p>\n<p><em>Benutzerdefinierte Vorfahrenliste<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14402\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Custom-Reports_DE.jpg\" alt=\"\" width=\"1919\" height=\"1040\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Custom-Reports_DE.jpg 1919w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Custom-Reports_DE-300x163.jpg 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Custom-Reports_DE-768x416.jpg 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Custom-Reports_DE-1024x555.jpg 1024w\" sizes=\"(max-width: 1919px) 100vw, 1919px\" \/><\/p>\n<p>Je nach gew\u00e4hlter Standardvorlage werden die Daten unterschiedlich angezeigt:<\/p>\n<ul>\n<li><strong>Personenlisten<\/strong> zeigen alle Personen in Ihrer Genealogie an.<\/li>\n<li><strong>Vorfahrenlisten<\/strong> zeigen die prim\u00e4re Person sowie deren Vorfahren, gruppiert nach Generationen, an.<\/li>\n<li><strong>Nachfahrenlisten<\/strong> zeigen die prim\u00e4re Person sowie deren Nachfahren, gruppiert nach Generationen, an.<\/li>\n<li><strong>Ereignislisten<\/strong> zeigen alle in Ihrer Genealogie gespeicherten Ereignisse an.<\/li>\n<li>Ab Heredis 2025: <strong>Pers\u00f6nliche Faktenliste<\/strong> zeigt alle pers\u00f6nlichen Fakten in Ihrer Datei.<strong><br \/>\n<\/strong><\/li>\n<li><strong>Ortslisten<\/strong> zeigen alle in Ihrer Genealogie gespeicherten Orte an.<\/li>\n<li><strong>Quellenlisten<\/strong> zeigen alle Quellen in Ihrer Genealogie an.<\/li>\n<\/ul>\n<p>Jede Liste enth\u00e4lt folgende Elemente:<\/p>\n<ul>\n<li>eine Symbolleiste<\/li>\n<li>eine Datentabelle<\/li>\n<li>eine Statusleiste<\/li>\n<\/ul>\n<p>Sie k\u00f6nnen in jeder Liste auf den Namen einer Person klicken und in Heredis zu dieser Person navigieren.<\/p>\n<h3>Die Symbolleiste<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14405\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Toolbar_DE.jpg\" alt=\"\" width=\"563\" height=\"60\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Toolbar_DE.jpg 563w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Toolbar_DE-300x32.jpg 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Toolbar_DE-560x60.jpg 560w\" sizes=\"(max-width: 563px) 100vw, 563px\" \/><\/p>\n<h4><img decoding=\"async\" class=\"alignnone size-full wp-image-1858\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/Ajouter.png\" alt=\"\" width=\"32\" height=\"32\" \/><strong> Hinzuf\u00fcgen<\/strong><\/h4>\n<p>W\u00e4hlen Sie die Informationen, die Sie Ihrer Liste hinzuf\u00fcgen m\u00f6chten, indem Sie auf die verschiedenen verf\u00fcgbaren Bereiche klicken (Personenbezogene Angaben, Medien, &#8230;)<br \/>\nSie k\u00f6nnen ein oder mehrere Felder unter den Vorschl\u00e4gen w\u00e4hlen. Durch Klicken auf OK werden automatisch weitere Spalten hinzugef\u00fcgt, damit Sie die f\u00fcr Sie relevanten und wichtigen Daten sehen k\u00f6nnen.<\/p>\n<p><strong>Hinweis:<\/strong> Sie k\u00f6nnen auch mehrere Felder in einer einzelnen Spalte gruppieren. W\u00e4hlen Sie die gew\u00fcnschten Felder und aktivieren Sie die Option <strong>In einer einzelnen Spalte gruppieren<\/strong>. Geben Sie der Spalte einen neuen Namen. Best\u00e4tigen Sie Ihre Wahl und wiederholen Sie den Vorgang f\u00fcr jede Spalte, in der Sie mehrere Felder gruppieren m\u00f6chten, z. B. Geburtsdatum und Geburtsort.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone size-full wp-image-47287\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_rubriques1DE.png\" alt=\"\" width=\"1504\" height=\"574\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_rubriques1DE.png 1504w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_rubriques1DE-300x114.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_rubriques1DE-1024x391.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_rubriques1DE-768x293.png 768w\" sizes=\"(max-width: 1504px) 100vw, 1504px\" \/><\/h4>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-269\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/11\/personaliser.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong>\u00a0 Optionen<\/strong><\/h4>\n<p>Je nach Art der Liste stehen Ihnen mehrere Optionen, Gruppierungsm\u00f6glichkeiten und Filter zur Verf\u00fcgung, um eine detailliertere Liste zu erstellen.<\/p>\n<p><em>\u2013 Personenliste:<\/em><br \/>\nDiese Liste basiert auf allen in Ihrer Genealogie gespeicherten Personen. M\u00f6chten Sie markierte Personen, sekund\u00e4re Personen, vertrauliche Personen, zeitgen\u00f6ssische Personen oder private Daten ber\u00fccksichtigen oder ausschlie\u00dfen, aktivieren\/deaktivieren Sie die entsprechenden Kontrollk\u00e4stchen.<br \/>\nHeredis wird in dieser Liste standardm\u00e4\u00dfig keine Personen gruppieren, aber Sie k\u00f6nnen Ihre eigene Anzeige gruppiert nach Namen oder Geburt konfigurieren.<br \/>\nSie k\u00f6nnen auch nur M\u00e4nner bzw. nur Frauen oder nur die Kekule-Linie w\u00e4hlen.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14597\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Personenliste1.jpg\" alt=\"\" width=\"708\" height=\"256\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Personenliste1.jpg 708w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Personenliste1-300x108.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/p>\n<p><em>\u2013 Vorfahrenliste:<\/em><br \/>\nDiese Liste basiert auf der angezeigten prim\u00e4ren Person.<br \/>\nM\u00f6chten Sie markierte Personen, sekund\u00e4re Personen, vertrauliche Personen, zeitgen\u00f6ssische Personen oder private Daten ber\u00fccksichtigen oder ausschlie\u00dfen, aktivieren\/deaktivieren Sie die entsprechenden Kontrollk\u00e4stchen.<br \/>\nHeredis wird standardm\u00e4\u00dfig eine komplette Liste Ihrer Vorfahren \u00fcber zehn Generationen anbieten, aber Sie k\u00f6nnen diese Optionen \u00e4ndern und nur eine Liste nach m\u00e4nnlichen Vorfahren (agnatisch) oder weiblichen Vorfahren (kognatisch) zusammenstellen. Sie k\u00f6nnen auch die Anzahl der angezeigten Generationen erh\u00f6hen oder verringern.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14431\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Vorfahrenliste.jpg\" alt=\"\" width=\"711\" height=\"262\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Vorfahrenliste.jpg 711w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Vorfahrenliste-300x111.jpg 300w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/><\/p>\n<p><em>\u2013 Nachfahrenliste:<\/em><br \/>\nDiese Liste basiert auf der angezeigten prim\u00e4ren Person.<br \/>\nM\u00f6chten Sie markierte Personen, sekund\u00e4re Personen, vertrauliche Personen, zeitgen\u00f6ssische Personen oder private Daten ber\u00fccksichtigen oder ausschlie\u00dfen, aktivieren\/deaktivieren Sie die entsprechenden Kontrollk\u00e4stchen.<br \/>\nHeredis wird standardm\u00e4\u00dfig eine komplette Liste Ihrer Nachfahren \u00fcber zehn Generationen anbieten, aber Sie k\u00f6nnen diese Optionen \u00e4ndern und sich z. B. nur die Tr\u00e4ger des Nachnamens der prim\u00e4ren Person anzeigen lassen. Sie k\u00f6nnen auch die Anzahl der Generationen erh\u00f6hen oder verringern und die Art der Nummerierung in Ihrer benutzerdefinierten Liste ausw\u00e4hlen (d\u2019Aboville oder Alphabetisch).<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14574\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Nachfahrenliste1.jpg\" alt=\"\" width=\"709\" height=\"266\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Nachfahrenliste1.jpg 709w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Nachfahrenliste1-300x113.jpg 300w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/p>\n<p><em>\u2013 Ereignisliste:<\/em><br \/>\nDiese Liste basiert auf allen in Ihrer Genealogie gespeicherten Ereignissen.<br \/>\nM\u00f6chten Sie markierte Personen, sekund\u00e4re Personen, vertrauliche Personen, zeitgen\u00f6ssische Personen oder private Daten ber\u00fccksichtigen oder ausschlie\u00dfen, aktivieren\/deaktivieren Sie die entsprechenden Kontrollk\u00e4stchen.<br \/>\nHeredis wird standardm\u00e4\u00dfig keine Gruppierung in dieser Liste vornehmen, aber Sie k\u00f6nnen Ihre eigene Anzeige der Ereignisse nach Daten, Personen, Orten oder nach Art der Ereignisse konfigurieren.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14437\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Ereignisliste.jpg\" alt=\"\" width=\"711\" height=\"452\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Ereignisliste.jpg 711w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Ereignisliste-300x191.jpg 300w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/><\/p>\n<p><em>\u2013Pers\u00f6nliche Faktenliste (Seit Heredis 2025):<br \/>\n<\/em><\/p>\n<p>Diese Liste basiert auf allen in Ihrer Genealogie gespeicherten pers\u00f6nlichen Fakten oder auf die Ergebnisse der Intelligenten Suche, wenn Sie eine Suche gestartet haben.<\/p>\n<p><em><img decoding=\"async\" class=\"alignnone  wp-image-54171\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE.png\" alt=\"\" width=\"924\" height=\"324\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE.png 2516w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE-300x105.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE-1024x359.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE-768x269.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE-1536x538.png 1536w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_rubriques_personnelles_DE-1920x673.png 1920w\" sizes=\"(max-width: 924px) 100vw, 924px\" \/>\u2013 <\/em><\/p>\n<p><em>Ortsliste:<\/em><br \/>\nDiese Liste basiert auf allen in Ihrer Genealogie gespeicherten Orte. Sie k\u00f6nnen Ihre Liste auf einen Ort, Kreis, ein Bundesland&#8230; einschr\u00e4nken.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone  wp-image-47290\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE.png\" alt=\"\" width=\"963\" height=\"258\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE.png 1716w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE-300x80.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE-1024x274.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE-768x206.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_lieuDE-1536x412.png 1536w\" sizes=\"(max-width: 963px) 100vw, 963px\" \/><\/h4>\n<p><em>\u2013 Quellenliste:<\/em><br \/>\nDiese Liste basiert auf allen in Ihrer Genealogie gespeicherten Quellen. Sie k\u00f6nnen Ihre eigene Anzeige der Quellen nach privaten Quellen, genutzte Quellen&#8230; konfigurieren.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone  wp-image-47293\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE.png\" alt=\"\" width=\"981\" height=\"232\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE.png 1714w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE-300x71.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE-1024x243.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE-768x182.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/option_liste_sourcesDE-1536x364.png 1536w\" sizes=\"(max-width: 981px) 100vw, 981px\" \/><\/h4>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-1924\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/palette.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong> Design<\/strong><\/h4>\n<p>Folgende Design-Optionen stehen Ihnen zur Verf\u00fcgung:<\/p>\n<ul>\n<li>Nachnamen, Vornamen, Daten<\/li>\n<li>Schriftgr\u00f6\u00dfe in der Liste<\/li>\n<li>Farben f\u00fcr M\u00e4nner, Frauen, Kekule-Nr. und 1. Kekule-Nr. bei Implex. Die auf dem Bildschirm angezeigten Farben werden in die Formate .xlsx und .csv exportiert.<\/li>\n<li>Hauptereignisse<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14606\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Layout-Button-2.jpg\" alt=\"\" width=\"708\" height=\"342\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Layout-Button-2.jpg 708w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Layout-Button-2-300x145.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/><\/p>\n<h4><strong><img decoding=\"async\" class=\"alignnone wp-image-1884\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/enregistrer.png\" alt=\"\" width=\"25\" height=\"25\" \/> Speichern<\/strong><\/h4>\n<p>Klicken Sie auf den Button <strong>Speichern<\/strong> und geben Sie einen Namen f\u00fcr Ihre Liste ein, damit diese mit Ihren benutzerdefinierten Optionen und Pr\u00e4ferenzen gespeichert wird.<\/p>\n<p>Diese finden Sie sp\u00e4ter wieder im Men\u00fc <strong>(Windows)<\/strong> <strong>Berichte &gt; Benutzerdefinierte Listen; (Mac) Dokumente &gt; Benutzerdefinierte Listen<\/strong> direkt unter der von Heredis angebotenen Standardvorlage.<\/p>\n<p>Sie k\u00f6nnen ebenfalls Ihre Vorlagen f\u00fcr benutzerdefinierte Listen verwalten. Mehr erfahren Sie im Abschnitt <strong>Vorlagen verwalten<\/strong>.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-1952\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/01\/supprimer.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong> L\u00f6schen<\/strong><\/h4>\n<p>\u00d6ffnen Sie \u00fcber das Men\u00fc <strong>(Windows)<\/strong> <strong>Berichte &gt; Benutzerdefinierte Listen; (Mac) Dokumente &gt; Benutzerdefinierte Listen<\/strong> die Vorlage, die Sie nicht behalten m\u00f6chten. Klicken Sie auf <strong>L\u00f6schen<\/strong> und best\u00e4tigen Sie, dass die Vorlage gel\u00f6scht werden soll.<\/p>\n<p>Sie k\u00f6nnen ebenfalls Ihre Vorlagen f\u00fcr benutzerdefinierte Listen l\u00f6schen. Mehr erfahren Sie im Abschnitt <strong>Vorlagen verwalten<\/strong>.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-1441\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2017\/12\/125-rafraichir.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong> Aktualisieren<\/strong><\/h4>\n<p>Die benutzerdefinierten Listen werden in einem unabh\u00e4ngigen Heredis-Fenster ge\u00f6ffnet, damit Sie an Ihrer Datei weiterarbeiten k\u00f6nnen, w\u00e4hrend eine benutzerdefinierte Liste ge\u00f6ffnet ist. Wenn Sie an Ihrer Genealogie \u00c4nderungen vornehmen oder Elemente hinzuf\u00fcgen, brauchen Sie nur auf den Button <strong>Aktualisieren<\/strong> zu klicken, um den Inhalt der angezeigten Liste zu aktualisieren.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-3726\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/Export-CSV.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong> CSV \/ <\/strong><img decoding=\"async\" class=\"alignnone wp-image-3727\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/Export-XLS.png\" alt=\"\" width=\"25\" height=\"25\" \/><strong> Excel<\/strong><\/h4>\n<p>Sie k\u00f6nnen die Daten aus Ihrer Liste in ein <strong>CSV- oder Excel-Format<\/strong> exportieren, damit Sie sie sp\u00e4ter au\u00dferhalb von Heredis nutzen k\u00f6nnen. Die Datei wird von Heredis unabh\u00e4ngig sein und Sie k\u00f6nnen die Datei mit Ihrem \u00fcblichen Tabellenkalkulationsprogramm bearbeiten.<\/p>\n<p>Heredis ist f\u00fcr die Textverarbeitungsprogramme Microsoft Office (kostenpflichtig) oder LibreOffice (kostenlos) optimiert, die bei den jeweiligen Anbietern heruntergeladen werden k\u00f6nnen.<\/p>\n<p><strong>Hinweis<\/strong>: Ein gutes Funktionieren garantieren wir mit Microsoft 365 (mind. Microsoft Office 2016) f\u00fcr Windows und Microsoft 365 (mind. Microsoft Office 2019) f\u00fcr Mac.<br \/>\nBitte achten Sie beim Programm LibreOffice darauf, dass Sie die aktuelle Version installiert haben.<\/p>\n<h3>Die Datentabelle<\/h3>\n<p>Die verschiedenen Listen zeigen Daten in einer Tabelle mit mehreren Spalten an; der Inhalt h\u00e4ngt jeweils von der von Ihnen gew\u00e4hlten Vorlage ab.<\/p>\n<p>Sie k\u00f6nnen die Daten sortieren, indem Sie auf den Titel einer Spalte klicken. Ein Pfeil neben dem Spaltentitel zeigt Ihnen an, wie die Daten sortiert wurden: ansteigend, absteigend oder keine Sortierung, wenn kein Pfeil angezeigt wird.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14453\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Date-of-Event-DE.jpg\" alt=\"\" width=\"229\" height=\"30\" \/><\/p>\n<p><strong>Hinweis:<\/strong> Einige Spalten k\u00f6nnen nicht sortiert werden. Dies betrifft zum Beispiel Spalten, in denen mehrere Arten von Daten gruppiert wurden. Ein Hinweis in Rot wird Ihnen anzeigen, dass die Spalte nicht sortiert werden kann.<\/p>\n<p>Sie k\u00f6nnen auch:<\/p>\n<ul>\n<li>durch Verschieben der Spalten die Anzeige Ihrer Daten neu organisieren: Klicken Sie den Titel einer Spalte und halten Sie die Maustaste gedr\u00fcckt, w\u00e4hrend Sie die Spalte an den gew\u00fcnschten Platz ziehen. Lassen Sie die gedr\u00fcckte Maustaste wieder los.<\/li>\n<li>eine Spalte l\u00f6schen: Klicken Sie auf die im Titel der Spalte angezeigten drei Punkte und w\u00e4hlen Sie die Option <strong>L\u00f6schen<\/strong>.<\/li>\n<li>den Inhalt einer Spalte \u00e4ndern: Klicken Sie auf die im Titel der Spalte angezeigten drei Punkte und w\u00e4hlen Sie die Option <strong>Bearbeiten<\/strong>. Ein Bearbeitungsfenster wird ge\u00f6ffnet.<br \/>\nSie k\u00f6nnen:<br \/>\n\u2013 den Titel der Spalte \u00e4ndern<br \/>\n\u2013 Felder in dieser Spalte hinzuf\u00fcgen\/\u00e4ndern\/l\u00f6schen<br \/>\n\u2013 Spaltentrennzeichen hinzuf\u00fcgen und personalisieren, um diese zwischen zwei Spaltenfeldern anzuzeigen.<\/li>\n<\/ul>\n<p><em>Eine Spalte bearbeiten oder l\u00f6schen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14443\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Edit-or-Delete-a-Column_DE.jpg\" alt=\"\" width=\"294\" height=\"87\" \/><\/p>\n<p><em>Daten organisieren<\/em><\/p>\n<h3 class=\"western\" lang=\"de-DE\"><img decoding=\"async\" class=\"alignnone  wp-image-47296\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_organisererDE.png\" alt=\"\" width=\"886\" height=\"176\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_organisererDE.png 1288w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_organisererDE-300x60.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_organisererDE-1024x204.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/liste_parametrable_organisererDE-768x153.png 768w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><\/h3>\n<h3 class=\"western\" lang=\"de-DE\">Die Statusleiste<\/h3>\n<p>In der Statusleiste zeigt Heredis die gesamte Seitenzahl der Liste sowie den Seitenbereich an, in dem sich die aktuelle Seite befindet (in der rechten unteren Ecke).<br \/>\nBl\u00e4ttern Sie ganz einfach durch Ihre Liste mit den Buttons <strong>Zur ersten Seite\/Zur letzten Seite, Zur vorherigen Seite\/Zur n\u00e4chsten Seite<\/strong>. Sie k\u00f6nnen auch durch Eingabe der Zahl eine bestimmte Seite abrufen.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14446\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Status-Bar_DE.jpg\" alt=\"\" width=\"282\" height=\"34\" \/><\/p>\n<h3>Benutzerdefinierte Listen und Intelligente Suche<\/h3>\n<p>Auf benutzerdefinierte Listen k\u00f6nnen Sie auch direkt von der Funktion <strong>Intelligente Suche<\/strong> zugreifen.<\/p>\n<p>\u2022 Starten Sie eine Suche \u00fcber die Registerkarte <strong>Suche<\/strong> <strong>&gt; Intelligente Suche<\/strong>.<br \/>\n\u2022 W\u00e4hlen Sie im Abschnitt <strong>Ergebnisse<\/strong> die Registerkarten <strong>Personen<\/strong> oder <strong>Ereignisse<\/strong>; je nachdem was Sie interessiert.<br \/>\n\u2022 Klicken Sie im Abschnitt <strong>Ausgew\u00e4hlte Personen\/Ereignisse bearbeiten<\/strong> auf <strong>Liste erstellen<\/strong> <strong>&gt; Benutzerdefinierte Listen<\/strong> und w\u00e4hlen Sie die Vorlage, mit der Sie Ihre Suchergebnisse anzeigen m\u00f6chten.<\/p>\n<p><em>Windows: Intelligente Suche und benutzerdefinierte Listen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47299\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE.png\" alt=\"\" width=\"1912\" height=\"976\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE.png 1912w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE-300x153.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE-1024x523.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE-768x392.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_riDE-1536x784.png 1536w\" sizes=\"(max-width: 1912px) 100vw, 1912px\" \/><\/p>\n<p><em>Mac: Intelligente Suche und benutzerdefinierte Listen<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-47302\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE.png\" alt=\"\" width=\"1900\" height=\"1075\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE.png 1900w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE-300x170.png 300w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE-1024x579.png 1024w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE-768x435.png 768w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/Liste_parametrable_ri-MacDE-1536x869.png 1536w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/><\/p>\n<h3>Vorlagen verwalten<\/h3>\n<p>Heredis erm\u00f6glicht Ihnen Ihre Vorlagen f\u00fcr die benutzerdefinierte Listen zu verwalten.<\/p>\n<p><strong>(Windows)<\/strong> Klicken Sie auf das Men\u00fc <strong>Berichte &gt; Benutzerdefinierte Listen &gt; Vorlagen verwalten \u2026<\/strong> und \u00f6ffnen Sie den Vorlagenverwalter.<\/p>\n<p><strong>(Mac)<\/strong> Klicken Sie auf das Men\u00fc <strong>Dokumente &gt; Benutzerdefinierte Listen &gt; Vorlagen verwalten \u2026<\/strong> und \u00f6ffnen Sie den Vorlagenverwalter.<\/p>\n<p><em>Windows: Vorlagen von benutzerdefinierten Listen verwalten<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-14603\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Vorlagen-verwalten.jpg\" alt=\"\" width=\"448\" height=\"348\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Vorlagen-verwalten.jpg 448w, https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/09\/Vorlagen-verwalten-300x233.jpg 300w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/><\/p>\n<p><em>Mac: Vorlagen von benutzerdefinierten Listen verwalten<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-17012\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/CustomListMac_DE-1.png\" alt=\"\" width=\"455\" height=\"632\" srcset=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/CustomListMac_DE-1.png 792w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/CustomListMac_DE-1-216x300.png 216w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/CustomListMac_DE-1-737x1024.png 737w, https:\/\/help.heredis.com\/wp-content\/uploads\/2020\/01\/CustomListMac_DE-1-768x1067.png 768w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>W\u00e4hlen Sie die Vorlage, die Sie \u00e4ndern m\u00f6chten, und klicken Sie auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-11945\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/Edit.png\" alt=\"\" width=\"16\" height=\"16\" \/>, um diese Vorlage umzubenennen oder auf den Button <img decoding=\"async\" class=\"alignnone size-full wp-image-11954\" src=\"https:\/\/help.heredis.com\/wp-content\/uploads\/2019\/08\/16-moins-1.jpg\" alt=\"\" width=\"16\" height=\"16\" \/>, um die Vorlage zu l\u00f6schen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Funktion bietet Ihnen verschiedene Vorlagen, die Sie je nach Bedarf komplett personalisieren k\u00f6nnen.<\/p>\n<p>Klicken Sie auf das Men\u00fc (Windows [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[99,137,143,160],"class_list":["post-12188","post","type-post","status-publish","format-standard","hentry","category-heredis-anwenden","tag-les-differents-documents","tag-the-differents-documents-de","tag-die-verschiedenen-dokumente","tag-ergebnisdarstellungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Benutzerdefinierte Listen - Heredis Help Knowledgebase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benutzerdefinierte Listen - Heredis Help Knowledgebase\" \/>\n<meta property=\"og:description\" content=\"Diese Funktion bietet Ihnen verschiedene Vorlagen, die Sie je nach Bedarf komplett personalisieren k\u00f6nnen.  Klicken Sie auf das Men\u00fc (Windows [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/\" \/>\n<meta property=\"og:site_name\" content=\"Heredis Help Knowledgebase\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-07T09:11:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T08:18:54+00:00\" \/>\n<meta name=\"author\" content=\"help_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"help_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"14\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/\"},\"author\":{\"name\":\"help_admin\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"headline\":\"Benutzerdefinierte Listen\",\"datePublished\":\"2020-01-07T09:11:50+00:00\",\"dateModified\":\"2025-09-01T08:18:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/\"},\"wordCount\":1588,\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/listes-params.png\",\"keywords\":[\"Les diff\u00e9rents documents\",\"The differents documents\",\"Die verschiedenen Dokumente\",\"Ergebnisdarstellungen\"],\"articleSection\":[\"Heredis anwenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/\",\"name\":\"Benutzerdefinierte Listen - Heredis Help Knowledgebase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/listes-params.png\",\"datePublished\":\"2020-01-07T09:11:50+00:00\",\"dateModified\":\"2025-09-01T08:18:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/listes-params.png\",\"contentUrl\":\"https:\\\/\\\/help.heredis.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/listes-params.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/benutzerdefinierte-listen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benutzerdefinierte Listen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#website\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/\",\"name\":\"Heredis Help Knowledgebase\",\"description\":\"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/help.heredis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/help.heredis.com\\\/#\\\/schema\\\/person\\\/0e1cc097410e0da5c58586a09469b26f\",\"name\":\"help_admin\",\"url\":\"https:\\\/\\\/help.heredis.com\\\/de\\\/author\\\/help_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benutzerdefinierte Listen - Heredis Help Knowledgebase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/","og_locale":"de_DE","og_type":"article","og_title":"Benutzerdefinierte Listen - Heredis Help Knowledgebase","og_description":"Diese Funktion bietet Ihnen verschiedene Vorlagen, die Sie je nach Bedarf komplett personalisieren k\u00f6nnen.  Klicken Sie auf das Men\u00fc (Windows [...]","og_url":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/","og_site_name":"Heredis Help Knowledgebase","article_published_time":"2020-01-07T09:11:50+00:00","article_modified_time":"2025-09-01T08:18:54+00:00","author":"help_admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"help_admin","Gesch\u00e4tzte Lesezeit":"14\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#article","isPartOf":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/"},"author":{"name":"help_admin","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"headline":"Benutzerdefinierte Listen","datePublished":"2020-01-07T09:11:50+00:00","dateModified":"2025-09-01T08:18:54+00:00","mainEntityOfPage":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/"},"wordCount":1588,"image":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/listes-params.png","keywords":["Les diff\u00e9rents documents","The differents documents","Die verschiedenen Dokumente","Ergebnisdarstellungen"],"articleSection":["Heredis anwenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/","url":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/","name":"Benutzerdefinierte Listen - Heredis Help Knowledgebase","isPartOf":{"@id":"https:\/\/help.heredis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#primaryimage"},"image":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#primaryimage"},"thumbnailUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/listes-params.png","datePublished":"2020-01-07T09:11:50+00:00","dateModified":"2025-09-01T08:18:54+00:00","author":{"@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f"},"breadcrumb":{"@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#primaryimage","url":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/listes-params.png","contentUrl":"https:\/\/help.heredis.com\/wp-content\/uploads\/2018\/07\/listes-params.png"},{"@type":"BreadcrumbList","@id":"https:\/\/help.heredis.com\/de\/benutzerdefinierte-listen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/help.heredis.com\/de\/"},{"@type":"ListItem","position":2,"name":"Benutzerdefinierte Listen"}]},{"@type":"WebSite","@id":"https:\/\/help.heredis.com\/#website","url":"https:\/\/help.heredis.com\/","name":"Heredis Help Knowledgebase","description":"Toutes les connaissances Heredis \u00e0 port\u00e9e de recherche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/help.heredis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/help.heredis.com\/#\/schema\/person\/0e1cc097410e0da5c58586a09469b26f","name":"help_admin","url":"https:\/\/help.heredis.com\/de\/author\/help_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/comments?post=12188"}],"version-history":[{"count":31,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12188\/revisions"}],"predecessor-version":[{"id":54174,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/posts\/12188\/revisions\/54174"}],"wp:attachment":[{"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/media?parent=12188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/categories?post=12188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/help.heredis.com\/de\/wp-json\/wp\/v2\/tags?post=12188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}